{"id":862,"date":"2025-10-09T09:41:22","date_gmt":"2025-10-09T09:41:22","guid":{"rendered":"https:\/\/mentaliza.page\/wallsolutions\/?page_id=862"},"modified":"2025-11-19T18:26:05","modified_gmt":"2025-11-19T18:26:05","slug":"projects","status":"publish","type":"page","link":"https:\/\/wallsolutions.es\/en\/projects\/","title":{"rendered":"Projects"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-d43d0c88 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div data-aos= \"fade-right\" data-aos-duration=\"2000\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-advanced-heading uagb-block-8f5d1181\"><p class=\"uagb-desc-text\">OUR PORTFOLIO<\/p><h1 class=\"uagb-heading-text\">Showcasing Excellence in Retaining Walls and Slope Stabilisation.<\/h1><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-7225cbb4 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-6fe18104\">\n<h2 class=\"wp-block-heading\">Eco Wall<\/h2>\n\n\n\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-fe5341bd     \"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--isogrid spectra-image-gallery__layout--isogrid-col-3 spectra-image-gallery__layout--isogrid-col-tab-3 spectra-image-gallery__layout--isogrid-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"865\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_1-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_1-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_1-300x225.jpg\" alt=\"Eco Wall - Estepona\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Wall &#8211; Estepona\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"867\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_2-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_2-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_2-300x225.jpg\" alt=\"Eco Wall - Los Flamingos\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Wall &#8211; Los Flamingos\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"869\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen-1024x576.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen-1024x576.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen-300x169.jpg\" alt=\"Eco Wall - Finca Oj\u00e9n\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Wall &#8211; Finca Oj\u00e9n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"871\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_quinta-1024x576.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_quinta-1024x576.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_quinta-300x169.jpg\" alt=\"Eco Wall - La Quinta\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Wall &#8211; La Quinta\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"873\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_1-1024x576.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_1-1024x576.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_1-300x169.jpg\" alt=\"Eco Wall - Granada FC\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Wall &#8211; Granada FC\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"875\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona_1-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona_1-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona_1-300x225.jpg\" alt=\"Eco Wall - Estepona Hospital\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Wall &#8211; Estepona Hospital\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__control-wrapper\">\n\t\t\t\t<button data-role=\"none\" class=\"spectra-image-gallery__control-arrows spectra-image-gallery__control-arrows--grid\" aria-label=\"Previous\" tabindex=\"0\" data-direction=\"Prev\" disabled>\n\t\t\t\t\t<svg width=\"20\" height=\"20\" viewbox=\"0 0 256 512\" aria-hidden=\"true\">\n\t\t\t\t\t\t<path d=\"M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\">\n\t\t\t\t\t\t<\/path>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/button>\n\t\t\t\t<ul class=\"spectra-image-gallery__control-dots\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"spectra-image-gallery__control-dot spectra-image-gallery__control-dot--active\" data-go-to=\"1\">\n\t\t\t\t\t\t\t<button aria-label=\"Page 1\"><\/button>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"spectra-image-gallery__control-dot\" data-go-to=\"2\">\n\t\t\t\t\t\t\t<button aria-label=\"Page 2\"><\/button>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"spectra-image-gallery__control-dot\" data-go-to=\"3\">\n\t\t\t\t\t\t\t<button aria-label=\"Page 3\"><\/button>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"spectra-image-gallery__control-dot\" data-go-to=\"4\">\n\t\t\t\t\t\t\t<button aria-label=\"Page 4\"><\/button>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"spectra-image-gallery__control-dot\" data-go-to=\"5\">\n\t\t\t\t\t\t\t<button aria-label=\"Page 5\"><\/button>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"spectra-image-gallery__control-dot\" data-go-to=\"6\">\n\t\t\t\t\t\t\t<button aria-label=\"Page 6\"><\/button>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"spectra-image-gallery__control-dot\" data-go-to=\"7\">\n\t\t\t\t\t\t\t<button aria-label=\"Page 7\"><\/button>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"spectra-image-gallery__control-dot\" data-go-to=\"8\">\n\t\t\t\t\t\t\t<button aria-label=\"Page 8\"><\/button>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<button data-role=\"none\" class=\"spectra-image-gallery__control-arrows spectra-image-gallery__control-arrows--grid\" aria-label=\"Next\" tabindex=\"0\" data-direction=\"Next\">\n\t\t\t\t\t<svg width=\"20\" height=\"20\" viewbox=\"0 0 256 512\" aria-hidden=\"true\">\n\t\t\t\t\t\t<path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\">\n\t\t\t\t\t\t<\/path>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/button>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class='spectra-image-gallery__control-lightbox' tabindex='0'>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper spectra-image-gallery__control-lightbox--main\" dir=\"\">\n\t\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_1.jpg\" alt=\"Eco Wall - Estepona\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_2.jpg\" alt=\"Eco Wall - Los Flamingos\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen.jpg\" alt=\"Eco Wall - Finca Oj\u00e9n\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_quinta.jpg\" alt=\"Eco Wall - La Quinta\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_1.jpg\" alt=\"Eco Wall - Granada FC\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona_1.jpg\" alt=\"Eco Wall - Estepona Hospital\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_marbella_hill_club.jpg\" alt=\"Eco Wall - Marbella Hill Club\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_F26.jpg\" alt=\"Eco Wall - Monte Mayor\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_1.jpg\" alt=\"Eco Wall - Finca Oj\u00e9n\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_2.jpg\" alt=\"Eco Wall - La Zagaleta\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_2.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29_1.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_2.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera_1.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_1.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_3.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_mijas.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_2.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_1.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_2.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benahavis.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_1.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_01.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benidorm.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_2.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_3.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_A6.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja_1.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_1.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_3.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares_1.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_1.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_2.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_tavira_portugal.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_2.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t\t\t<\/div>\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<button class='spectra-image-gallery__control-lightbox--close' aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\n\n<div style=\"height:148px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Iron Grid (Gaviones)<\/h2>\n\n\n\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-4547cc99     \"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--isogrid spectra-image-gallery__layout--isogrid-col-3 spectra-image-gallery__layout--isogrid-col-tab-3 spectra-image-gallery__layout--isogrid-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"966\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_2-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_2-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_2-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tIron Grid &#8211; Sevilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"968\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_7-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_7-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_7-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tIron Grid &#8211; Mijas\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"970\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_6-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_6-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_6-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tIron Grid &#8211; Mijas\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"972\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_5-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_5-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_5-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tIron Grid &#8211; Mijas\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"974\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_4-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_4-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_4-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tIron Grid &#8211; Mijas\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"976\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_3-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_3-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_3-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tIron Grid &#8211; Mijas\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"978\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_3-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_3-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_3-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tIron Grid &#8211; Sevilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"980\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tIron Grid &#8211; Sevilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"982\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_3-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_3-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_3-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tIron Grid &#8211; Monte Mayor\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__control-wrapper\">\n\t\t\t\t<button data-role=\"none\" class=\"spectra-image-gallery__control-arrows spectra-image-gallery__control-arrows--grid\" aria-label=\"Previous\" tabindex=\"0\" data-direction=\"Prev\" disabled>\n\t\t\t\t\t<svg width=\"20\" height=\"20\" viewbox=\"0 0 256 512\" aria-hidden=\"true\">\n\t\t\t\t\t\t<path d=\"M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\">\n\t\t\t\t\t\t<\/path>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/button>\n\t\t\t\t<ul class=\"spectra-image-gallery__control-dots\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"spectra-image-gallery__control-dot spectra-image-gallery__control-dot--active\" data-go-to=\"1\">\n\t\t\t\t\t\t\t<button aria-label=\"Page 1\"><\/button>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"spectra-image-gallery__control-dot\" data-go-to=\"2\">\n\t\t\t\t\t\t\t<button aria-label=\"Page 2\"><\/button>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"spectra-image-gallery__control-dot\" data-go-to=\"3\">\n\t\t\t\t\t\t\t<button aria-label=\"Page 3\"><\/button>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<button data-role=\"none\" class=\"spectra-image-gallery__control-arrows spectra-image-gallery__control-arrows--grid\" aria-label=\"Next\" tabindex=\"0\" data-direction=\"Next\">\n\t\t\t\t\t<svg width=\"20\" height=\"20\" viewbox=\"0 0 256 512\" aria-hidden=\"true\">\n\t\t\t\t\t\t<path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\">\n\t\t\t\t\t\t<\/path>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/button>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class='spectra-image-gallery__control-lightbox' tabindex='0'>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper spectra-image-gallery__control-lightbox--main\" dir=\"\">\n\t\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_2.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_7.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_6.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_5.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_4.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_3.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_3.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_3.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_2.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_7.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_6.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_5.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_4.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_3.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_2.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_estepona.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_madrid.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja_2.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_2.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t\t\t<\/div>\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<button class='spectra-image-gallery__control-lightbox--close' aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\n\n<div style=\"height:148px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Eco Block<\/h2>\n\n\n\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-5cc8c098     \"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--isogrid spectra-image-gallery__layout--isogrid-col-3 spectra-image-gallery__layout--isogrid-col-tab-3 spectra-image-gallery__layout--isogrid-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"1014\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_2-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_2-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_2-300x225.jpg\" alt=\"Eco Block Wall\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Block Wall\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"1016\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_7-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_7-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_7-300x225.jpg\" alt=\"Eco Block Wall\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Block Wall\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"1018\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_8-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_8-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_8-300x225.jpg\" alt=\"Eco Block Wall\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Block Wall\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"1020\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_13-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_13-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_13-300x225.jpg\" alt=\"Eco Block Wall\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Block Wall\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"1022\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_14-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_14-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_14-300x225.jpg\" alt=\"Eco Block Wall\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Block Wall\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"1024\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_15-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_15-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_15-300x225.jpg\" alt=\"Eco Block Wall\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Block Wall\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"1026\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block-300x225.jpg\" alt=\"Eco Block Wall\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Block Wall\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"1028\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_3-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_3-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_3-300x225.jpg\" alt=\"Eco Block Wall\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Block Wall\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper--isotope\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"1030\" tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_4-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_4-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_4-300x225.jpg\" alt=\"Eco Block Wall\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tEco Block Wall\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__control-wrapper\">\n\t\t\t\t<button data-role=\"none\" class=\"spectra-image-gallery__control-arrows spectra-image-gallery__control-arrows--grid\" aria-label=\"Previous\" tabindex=\"0\" data-direction=\"Prev\" disabled>\n\t\t\t\t\t<svg width=\"20\" height=\"20\" viewbox=\"0 0 256 512\" aria-hidden=\"true\">\n\t\t\t\t\t\t<path d=\"M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\">\n\t\t\t\t\t\t<\/path>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/button>\n\t\t\t\t<ul class=\"spectra-image-gallery__control-dots\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"spectra-image-gallery__control-dot spectra-image-gallery__control-dot--active\" data-go-to=\"1\">\n\t\t\t\t\t\t\t<button aria-label=\"Page 1\"><\/button>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"spectra-image-gallery__control-dot\" data-go-to=\"2\">\n\t\t\t\t\t\t\t<button aria-label=\"Page 2\"><\/button>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<button data-role=\"none\" class=\"spectra-image-gallery__control-arrows spectra-image-gallery__control-arrows--grid\" aria-label=\"Next\" tabindex=\"0\" data-direction=\"Next\">\n\t\t\t\t\t<svg width=\"20\" height=\"20\" viewbox=\"0 0 256 512\" aria-hidden=\"true\">\n\t\t\t\t\t\t<path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\">\n\t\t\t\t\t\t<\/path>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/button>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class='spectra-image-gallery__control-lightbox' tabindex='0'>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper spectra-image-gallery__control-lightbox--main\" dir=\"\">\n\t\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_2.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_7.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_8.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_13.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_14.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_15.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_3.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_4.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_5.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_9.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_10.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_11.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_12.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_1.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_6.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_16.jpg\" alt=\"Eco Block Wall\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t\t\t<\/div>\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<button class='spectra-image-gallery__control-lightbox--close' aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-d3a06ec4 alignfull uagb-is-root-container\"><div class=\"uagb-container__video-wrap\"><video autoplay loop muted playsinline><source src=\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/video-cta-isolutions-octubre-2025_LR.mp4\" type=\"video\/mp4\"\/><\/video><\/div><div class=\"uagb-container-inner-blocks-wrap\">\n<div data-aos= \"fade-right\" data-aos-duration=\"2000\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-info-box uagb-block-92f0d55a uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><span class=\"uagb-ifb-title-prefix\">Get In Touch<\/span><h2 class=\"uagb-ifb-title\">Kickstart Your Vision with Us Today!<\/h2><\/div><p class=\"uagb-ifb-desc\">Contact our experts now and let&#8217;s create the perfect solution tailored for your needs.<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"\/en\/contact\/\" class=\"uagb-infobox-cta-link wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\" onclick=\"return true;\"><span class=\"uagb-inline-editing\">Get Started<\/span><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M504.3 273.6l-112.1 104c-6.992 6.484-17.18 8.218-25.94 4.406c-8.758-3.812-14.42-12.45-14.42-21.1L351.9 288H32C14.33 288 .0002 273.7 .0002 255.1S14.33 224 32 224h319.9l0-72c0-9.547 5.66-18.19 14.42-22c8.754-3.809 18.95-2.075 25.94 4.41l112.1 104C514.6 247.9 514.6 264.1 504.3 273.6z\"><\/path><\/svg><\/a><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>OUR PORTFOLIO Showcasing Excellence in Retaining Walls and Slope Stabilisation. Eco Wall Iron Grid (Gaviones) Eco Block<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-862","page","type-page","status-publish","hentry"],"spectra_custom_meta":{"_customize_changeset_uuid":["52d10925-bd78-4988-af19-a81eb4e7c763"],"_uag_custom_page_level_css":[""],"site-post-title":["disabled"],"theme-transparent-header-meta":["enabled"],"adv-header-id-meta":[""],"stick-header-meta":[""],"footnotes":[""],"_wpml_word_count":["23"],"_wpml_location_migration_done":["1"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_dp_original":["279"],"_edit_lock":["1763577607:3"],"_edit_last":["3"],"_wpml_post_translation_editor_native":["yes"],"_uag_css_file_name":["uag-css-862.css"],"_uag_js_file_name":["uag-js-862.js"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:1;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:3;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:3;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uagb_last_spectra_edit":["1776818142"],"_uag_page_assets":["a:9:{s:3:\"css\";s:111709:\".uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.wp-block-uagb-container.uagb-block-d3a06ec4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d3a06ec4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d3a06ec4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d3a06ec4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d3a06ec4 .uagb-container__video-wrap video{opacity: 0.5;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d3a06ec4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d3a06ec4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d3a06ec4.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 0px;column-gap: 80px;grid-template-columns: minmax( 1px, 55%) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: center;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-d3a06ec4 .uagb-container__video-wrap{background: var(--ast-global-color-8);;border-color: inherit;}.wp-block-uagb-container.uagb-block-d3a06ec4 > div:not(.uagb-container__video-wrap):not(.uagb-container__shape){position: relative;}.wp-block-uagb-container.uagb-block-d3a06ec4{box-shadow: 0px 0px   #00000070 ;padding-top: 100px;padding-bottom: 100px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;row-gap: 0px;column-gap: 80px;overflow: visible;}.uagb-block-92f0d55a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-92f0d55a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-92f0d55a .uagb-ifb-icon svg{fill: #333;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-92f0d55a .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-92f0d55a .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-92f0d55a .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-92f0d55a .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-92f0d55a .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-92f0d55a .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-92f0d55a .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: #ffffff;margin-bottom: 14px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-92f0d55a .uagb-ifb-title{font-weight: 100;font-size: 61px;color: #ffffff;margin-bottom: 14px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-92f0d55a .uagb-ifb-desc{font-weight: 100;color: #ffffff;margin-bottom: 32px;margin-top: 0px;margin-left: 0px;margin-right: 115px;}.uagb-block-92f0d55a .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-92f0d55a .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-92f0d55a .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-92f0d55a .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-92f0d55a .uagb-infobox__content-wrap{text-align: left;}.uagb-block-92f0d55a.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-92f0d55a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 29%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-92f0d55a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 29%;padding-bottom: 0%;padding-left: 0%;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-92f0d55a .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link{color: #ffffff;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{color: #ffffff;background-color: transparent;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #ffffff;border-style: solid;}.uagb-block-92f0d55a .uagb-ifb-button-wrapper .uagb-infobox-cta-link svg{fill: #ffffff;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link:hover{color: #ffffff;}.uagb-block-92f0d55a .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link:hover > svg{fill: #ffffff;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link:focus{color: #ffffff;}.uagb-block-92f0d55a .uagb-infobox-cta-link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #ffffff;border-style: solid;}.uagb-block-92f0d55a .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 700;font-size: 14px;line-height: 1.6em;letter-spacing: 1px;}[dir=rtl] .uagb-block-92f0d55a .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-92f0d55a.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-92f0d55a.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-92f0d55a.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-d3a06ec4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d3a06ec4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d3a06ec4.uagb-layout-grid > .uagb-container-inner-blocks-wrap{column-gap: 40px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-d3a06ec4{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;column-gap: 40px;}.uagb-block-92f0d55a .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-92f0d55a .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-92f0d55a .uagb-ifb-desc{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-92f0d55a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-92f0d55a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-92f0d55a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-92f0d55a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-92f0d55a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 13%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-92f0d55a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 13%;padding-bottom: 0%;padding-left: 0%;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-92f0d55a .uagb-infobox-cta-link{border-style: solid;border-color: #ffffff;}.uagb-block-92f0d55a .uagb-ifb-title-prefix{font-size: 14px;line-height: 1.6em;letter-spacing: 1px;}[dir=rtl] .uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-d3a06ec4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d3a06ec4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d3a06ec4.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 40px;column-gap: 0px;grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-d3a06ec4{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;row-gap: 40px;column-gap: 0px;}.uagb-block-92f0d55a .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-92f0d55a .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-92f0d55a .uagb-ifb-desc{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-92f0d55a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-92f0d55a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-92f0d55a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-92f0d55a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-92f0d55a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-92f0d55a .uagb-infobox-cta-link{border-style: solid;border-color: #ffffff;}.uagb-block-92f0d55a .uagb-ifb-title-prefix{font-size: 14px;line-height: 1.6em;letter-spacing: 1px;}[dir=rtl] .uagb-block-92f0d55a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}\ufeff.wp-block-uagb-image-gallery{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;-webkit-justify-content:center;justify-content:center;flex-direction:column}.spectra-image-gallery *{box-sizing:border-box}.spectra-image-gallery__layout--grid{display:-moz-grid;display:-ms-grid;display:grid;grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--grid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__layout--isogrid-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--isogrid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__layout--masonry-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--carousel{width:100%}.spectra-image-gallery__layout--carousel .slick-initialized{visibility:visible}.spectra-image-gallery__layout--carousel .slick-track{display:flex;align-items:center}.spectra-image-gallery__layout--carousel .slick-slide .spectra-image-gallery__media-wrapper{display:block !important}.spectra-image-gallery__layout--carousel .slick-dots{padding:0;position:relative !important}.spectra-image-gallery__layout--carousel .slick-dots li button{padding:0}.spectra-image-gallery__layout--carousel .uagb-slick-carousel{padding:0}.spectra-image-gallery__layout--tiled{position:relative;display:grid;grid-auto-flow:dense;min-height:0;min-width:0}.spectra-image-gallery__layout--tiled-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__media{position:relative;overflow:hidden;-webkit-transition:box-shadow .25s;-moz-transition:box-shadow .25s;-o-transition:box-shadow .25s;transition:box-shadow .25s}.spectra-image-gallery__media--flagged{cursor:not-allowed}.spectra-image-gallery__media--clickable{cursor:pointer}.spectra-image-gallery__media--grid{aspect-ratio:1}.spectra-image-gallery__media--masonry{width:100%}.spectra-image-gallery__media--carousel{width:100%}.spectra-image-gallery__media--tiled{aspect-ratio:1;display:flex;align-items:center;justify-content:center}.spectra-image-gallery__media--tiled-wide,.spectra-image-gallery__media--tiled-tall{aspect-ratio:unset;width:100%;height:100%}.spectra-image-gallery__media--tiled picture{width:100%;height:100%}.spectra-image-gallery__media-sizer{aspect-ratio:1}.spectra-image-gallery__media-wrapper{position:relative}.spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__control-focus{opacity:.25}.spectra-image-gallery__media-thumbnail{vertical-align:middle;-webkit-transition:filter .5s,transform .5s;-moz-transition:filter .5s,transform .5s;-o-transition:filter .5s,transform .5s;transition:filter .5s,transform .5s}.spectra-image-gallery__media-thumbnail--grid{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail--masonry{width:100%}.spectra-image-gallery__media-thumbnail--carousel{width:100%}.spectra-image-gallery__media-thumbnail--tiled{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail-blurrer{position:absolute;top:0;left:0;width:100% !important;height:100% !important;-webkit-transition:box-shadow .25s,-webkit-backdrop-filter .5s;-moz-transition:box-shadow .25s,backdrop-filter .5s;-o-transition:box-shadow .25s,backdrop-filter .5s;transition:box-shadow .25s,backdrop-filter .5s}.spectra-image-gallery__media-thumbnail-caption{-webkit-transition-property:color,background-color,border-color;-moz-transition-property:color,background-color,border-color;-o-transition-property:color,background-color,border-color;transition-property:color,background-color,border-color;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__media-thumbnail-caption--overlay{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;height:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption--bar-inside{width:100%;overflow:hidden;padding:1em;max-height:90%}.spectra-image-gallery__media-thumbnail-caption--bar-outside{width:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption-wrapper{-webkit-transition:background-color .25s;-moz-transition:background-color .25s;-o-transition:background-color .25s;transition:background-color .25s}.spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{position:absolute;top:0;left:0;width:100%;height:100%}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{position:absolute;top:0;left:0;width:100%;height:100%;display:flex;overflow:hidden}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-outside{position:relative;width:100%;overflow:hidden}.spectra-image-gallery__control-wrapper{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;justify-content:center}.spectra-image-gallery__control-arrows{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;background-color:rgba(0,0,0,0);padding:0;cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-arrows:disabled{opacity:.25;cursor:initial}.spectra-image-gallery__control-arrows:focus{background-color:rgba(0,0,0,0)}.spectra-image-gallery__control-arrows--grid{border:none}.spectra-image-gallery__control-arrows svg{-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;padding:0 !important;margin:0 !important}.spectra-image-gallery__control-dots li{position:relative;display:inline-block;width:20px;height:20px;margin:0;padding:0;cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__control-dots li button{font-size:0;line-height:0;display:block;box-sizing:border-box;width:20px;height:20px;padding:5px;cursor:pointer;color:rgba(0,0,0,0);border:0;outline:none;background:rgba(0,0,0,0);-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li button::before{font-family:none;font-size:30px;line-height:20px;position:absolute;top:0;left:0;width:20px;height:20px;content:\"\u2022\";text-align:center;opacity:.25;-webkit-font-smoothing:antialiased;-moz-osx-font-smoothing:grayscale;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li.spectra-image-gallery__control-dot--active button::before{opacity:.75}.spectra-image-gallery__control-loader{margin:0 auto;min-height:58px;line-height:58px;width:160px;text-align:center}.spectra-image-gallery__control-loader div{border-radius:100%;display:inline-block;-webkit-animation:sk-bouncedelay 1.4s infinite ease-in-out both;animation:sk-bouncedelay 1.4s infinite ease-in-out both}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--1{-webkit-animation-delay:-0.32s;animation-delay:-0.32s}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--2{-webkit-animation-delay:-0.16s;animation-delay:-0.16s}.spectra-image-gallery__control-button{cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-button.disabled{opacity:.25;pointer-events:none}.spectra-image-gallery__control-focus{cursor:pointer;position:absolute;box-sizing:content-box !important;top:0;right:0;width:1.5em;height:1.5em;padding:.5em;background-color:rgba(0,0,0,0);border:none;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-focus:hover{opacity:1 !important}.spectra-image-gallery__control-focus svg{fill:#fff;filter:drop-shadow(1px 1px 1px rgba(0, 0, 0, 0.5))}.spectra-image-gallery__control-lightbox{position:fixed;top:0;left:0;width:100vw !important;max-width:100vw !important;height:100vh !important;max-height:100vh !important;display:flex;flex-direction:column;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;z-index:999999999 !important;outline:none;margin-block-start:0;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--main{width:100%;flex:1}.spectra-image-gallery__control-lightbox--main .swiper-slide{height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center}.spectra-image-gallery__control-lightbox--main .swiper-slide img{display:block;max-height:70%;max-width:80%}.spectra-image-gallery__control-lightbox--caption{position:absolute;bottom:0;left:0;width:100%;display:flex;align-items:center;justify-content:center;text-align:center}.spectra-image-gallery__control-lightbox--editor-link{-webkit-transition-property:color;-moz-transition-property:color;-o-transition-property:color;transition-property:color;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--thumbnails{width:75%}.spectra-image-gallery__control-lightbox--thumbnails-wrapper{width:100%}.spectra-image-gallery__control-lightbox--thumbnails .swiper-wrapper{height:150px}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide{cursor:pointer;height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center;opacity:.5;transform:scale(75%);-webkit-transition-property:opacity,transform;-moz-transition-property:opacity,transform;-o-transition-property:opacity,transform;transition-property:opacity,transform;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide-active{opacity:1;transform:scale(100%)}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide img{border-radius:3px}.spectra-image-gallery__control-lightbox--count{position:absolute;z-index:999}.spectra-image-gallery__control-lightbox--close{position:absolute;cursor:pointer;padding:0;background-color:rgba(0,0,0,0);border:none;outline:0;line-height:0;z-index:999;transition:transform 500ms}.spectra-image-gallery__control-lightbox--close:hover,.spectra-image-gallery__control-lightbox--close:focus,.spectra-image-gallery__control-lightbox--close:focus-visible{background-color:rgba(0,0,0,0);transform:scale(1.25)}.spectra-image-gallery__iso-ref-wrapper{-ms-overflow-style:none;scrollbar-width:none}.spectra-image-gallery__iso-ref-wrapper::-webkit-scrollbar{display:none}@media(max-width: 976px){.spectra-image-gallery__layout--grid-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}@media(max-width: 767px){.spectra-image-gallery__layout--grid-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}.entry-content .wp-block-uagb-image-gallery .uagb-image-gallery__link{text-decoration:none}body .wp-block-post-content>.wp-block-uagb-image-gallery+.spectra-image-gallery__control-lightbox{margin-block-start:0}@-webkit-keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}@keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}.wp-block-uagb-container.uagb-block-d43d0c88 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d43d0c88 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d43d0c88 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d43d0c88 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d43d0c88 .uagb-container__video-wrap video{opacity: 0.3;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d43d0c88{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d43d0c88 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-d43d0c88{box-shadow: 0px 0px   #00000070 ;padding-top: 200px;padding-bottom: 150px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_2.jpg);background-clip: padding-box;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-d43d0c88::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-7);opacity: 0.7;}.wp-block-uagb-advanced-heading.uagb-block-8f5d1181.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-8f5d1181.wp-block-uagb-advanced-heading {padding-top: 0%;padding-right: 25%;padding-bottom: 0%;padding-left: 0%;}.wp-block-uagb-advanced-heading.uagb-block-8f5d1181.wp-block-uagb-advanced-heading .uagb-desc-text{color: #ffffff;margin-bottom: 20px;}.wp-block-uagb-advanced-heading.uagb-block-8f5d1181.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8f5d1181.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8f5d1181.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8f5d1181 .uagb-heading-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-8f5d1181 .uagb-desc-text{text-transform: uppercase;font-weight: 700;font-size: 14px;line-height: 1.6em;letter-spacing: 1px;}.wp-block-uagb-container.uagb-block-7225cbb4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7225cbb4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7225cbb4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7225cbb4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7225cbb4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7225cbb4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7225cbb4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 60px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7225cbb4{box-shadow: 0px 0px   #00000070 ;padding-top: 100px;padding-bottom: 100px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: ;;row-gap: 60px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-6fe18104 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6fe18104 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6fe18104 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6fe18104 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6fe18104 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6fe18104{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6fe18104 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6fe18104.uagb-layout-grid{row-gap: 0px;column-gap: 80px;grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: center;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6fe18104{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: ;;}.uagb-block-fe5341bd.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-fe5341bd .spectra-image-gallery__control-arrows svg{fill: var(--ast-global-color-0);}.uagb-block-fe5341bd .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-fe5341bd .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-fe5341bd .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--carousel ul.slick-dots{top: 25px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: var(--ast-global-color-0);}.uagb-block-fe5341bd .spectra-image-gallery__control-dots li button::before{color: var(--ast-global-color-0);}.uagb-block-fe5341bd .spectra-image-gallery__control-loader{margin-top: 25px;}.uagb-block-fe5341bd .spectra-image-gallery__control-loader div{background-color: var(--ast-global-color-0);width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-fe5341bd .spectra-image-gallery__control-button{margin-top: 25px;padding:    ;background-color: var(--ast-global-color-0);font-style: normal;text-decoration: none;}.uagb-block-fe5341bd .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--carousel{margin-bottom: 25px !important;}.uagb-block-fe5341bd .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-fe5341bd .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.3);}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.3);}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.3);}.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: flex-end;align-items: flex-end;-webkit-justify-content: center;justify-content: center;}.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);text-align: center;font-style: normal;text-decoration: none;font-size: 11px;padding: 8px 8px 8px 8px;}.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: flex-end;align-items: flex-end;-webkit-justify-content: center;justify-content: center;}.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.3);}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.3);}.uagb-block-fe5341bdspectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.3);}.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.3);}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.3);}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.3);}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-fe5341bd .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-fe5341bd .spectra-image-gallery__control-wrapper{margin-top: 25px;}.uagb-block-fe5341bd .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-fe5341bd .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.spectra-touch-device.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption,.spectra-touch-device.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption-wrapper{transition:none !important;-webkit-backface-visibility:hidden;backface-visibility:hidden;}.spectra-touch-device.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay,.spectra-touch-device.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption--bar-inside{-webkit-backface-visibility:hidden;backface-visibility:hidden;-webkit-transform:translateZ(0);transform:translateZ(0);}@media(hover:none),(pointer:coarse){.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption,.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption-wrapper{transition:none !important;-webkit-backface-visibility:hidden;backface-visibility:hidden;}.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay,.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption--bar-inside{-webkit-backface-visibility:hidden;backface-visibility:hidden;-webkit-transform:translateZ(0);transform:translateZ(0);}}.uagb-block-4547cc99.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-4547cc99 .spectra-image-gallery__control-arrows svg{fill: var(--ast-global-color-0);}.uagb-block-4547cc99 .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-4547cc99 .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-4547cc99 .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--carousel ul.slick-dots{top: 25px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: var(--ast-global-color-0);}.uagb-block-4547cc99 .spectra-image-gallery__control-dots li button::before{color: var(--ast-global-color-0);}.uagb-block-4547cc99 .spectra-image-gallery__control-loader{margin-top: 25px;}.uagb-block-4547cc99 .spectra-image-gallery__control-loader div{background-color: var(--ast-global-color-0);width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-4547cc99 .spectra-image-gallery__control-button{margin-top: 25px;padding:    ;background-color: var(--ast-global-color-0);font-style: normal;text-decoration: none;}.uagb-block-4547cc99 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--carousel{margin-bottom: 25px !important;}.uagb-block-4547cc99 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-4547cc99 .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.3);}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.3);}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.3);}.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: flex-end;align-items: flex-end;-webkit-justify-content: center;justify-content: center;}.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);text-align: center;font-style: normal;text-decoration: none;font-size: 11px;padding: 8px 8px 8px 8px;}.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: flex-end;align-items: flex-end;-webkit-justify-content: center;justify-content: center;}.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.3);}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.3);}.uagb-block-4547cc99spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.3);}.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.3);}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.3);}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.3);}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-4547cc99 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-4547cc99 .spectra-image-gallery__control-wrapper{margin-top: 25px;}.uagb-block-4547cc99 .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-4547cc99 .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.spectra-touch-device.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption,.spectra-touch-device.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption-wrapper{transition:none !important;-webkit-backface-visibility:hidden;backface-visibility:hidden;}.spectra-touch-device.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay,.spectra-touch-device.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption--bar-inside{-webkit-backface-visibility:hidden;backface-visibility:hidden;-webkit-transform:translateZ(0);transform:translateZ(0);}@media(hover:none),(pointer:coarse){.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption,.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption-wrapper{transition:none !important;-webkit-backface-visibility:hidden;backface-visibility:hidden;}.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay,.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption--bar-inside{-webkit-backface-visibility:hidden;backface-visibility:hidden;-webkit-transform:translateZ(0);transform:translateZ(0);}}.uagb-block-5cc8c098.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-5cc8c098 .spectra-image-gallery__control-arrows svg{fill: var(--ast-global-color-0);}.uagb-block-5cc8c098 .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-5cc8c098 .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-5cc8c098 .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--carousel ul.slick-dots{top: 25px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: var(--ast-global-color-0);}.uagb-block-5cc8c098 .spectra-image-gallery__control-dots li button::before{color: var(--ast-global-color-0);}.uagb-block-5cc8c098 .spectra-image-gallery__control-loader{margin-top: 25px;}.uagb-block-5cc8c098 .spectra-image-gallery__control-loader div{background-color: var(--ast-global-color-0);width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-5cc8c098 .spectra-image-gallery__control-button{margin-top: 25px;padding:    ;background-color: var(--ast-global-color-0);font-style: normal;text-decoration: none;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--carousel{margin-bottom: 25px !important;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-5cc8c098 .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.3);}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.3);}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.3);}.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: flex-end;align-items: flex-end;-webkit-justify-content: center;justify-content: center;}.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);text-align: center;font-style: normal;text-decoration: none;font-size: 11px;padding: 8px 8px 8px 8px;}.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: flex-end;align-items: flex-end;-webkit-justify-content: center;justify-content: center;}.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.3);}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.3);}.uagb-block-5cc8c098spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.3);}.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.3);}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.3);}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.3);}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-5cc8c098 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-5cc8c098 .spectra-image-gallery__control-wrapper{margin-top: 25px;}.uagb-block-5cc8c098 .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.spectra-touch-device.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption,.spectra-touch-device.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption-wrapper{transition:none !important;-webkit-backface-visibility:hidden;backface-visibility:hidden;}.spectra-touch-device.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay,.spectra-touch-device.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption--bar-inside{-webkit-backface-visibility:hidden;backface-visibility:hidden;-webkit-transform:translateZ(0);transform:translateZ(0);}@media(hover:none),(pointer:coarse){.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption,.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption-wrapper{transition:none !important;-webkit-backface-visibility:hidden;backface-visibility:hidden;}.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay,.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption--bar-inside{-webkit-backface-visibility:hidden;backface-visibility:hidden;-webkit-transform:translateZ(0);transform:translateZ(0);}}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-d43d0c88{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d43d0c88 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d43d0c88{padding-top: 200px;padding-bottom: 100px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_2.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-d43d0c88::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-7);opacity: 0.7;}.wp-block-uagb-advanced-heading.uagb-block-8f5d1181.wp-block-uagb-advanced-heading {padding-top: 0%;padding-right: 6%;padding-bottom: 0%;padding-left: 0%;}.wp-block-uagb-advanced-heading.uagb-block-8f5d1181.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 12px;}.wp-block-uagb-advanced-heading.uagb-block-8f5d1181 .uagb-desc-text{font-size: 14px;line-height: 1.6em;letter-spacing: 1px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7225cbb4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7225cbb4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7225cbb4{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: ;;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6fe18104{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6fe18104 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6fe18104.uagb-layout-grid{column-gap: 40px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: center;justify-items: stretch;align-content: center;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6fe18104{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: ;;}.uagb-block-fe5341bd.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-fe5341bd .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-fe5341bd .spectra-image-gallery__control-button{padding:    ;}.uagb-block-fe5341bd .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-4547cc99.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-4547cc99 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-4547cc99 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-4547cc99 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-5cc8c098.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-5cc8c098 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-5cc8c098 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-d43d0c88{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d43d0c88 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d43d0c88{padding-top: 140px;padding-bottom: 80px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_2.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-d43d0c88::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-7);opacity: 0.7;}.wp-block-uagb-advanced-heading.uagb-block-8f5d1181.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-8f5d1181.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 10px;}.wp-block-uagb-advanced-heading.uagb-block-8f5d1181 .uagb-desc-text{font-size: 14px;line-height: 1.6em;letter-spacing: 1px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7225cbb4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7225cbb4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-7225cbb4{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;background-color: ;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6fe18104{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6fe18104 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6fe18104.uagb-layout-grid{row-gap: 35px;grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-6fe18104{padding-top: 0px;padding-bottom: 24px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 35px;order: initial;background-color: ;;}.uagb-block-fe5341bd.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-fe5341bd .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-fe5341bd .spectra-image-gallery__control-button{padding:    ;}.uagb-block-fe5341bd .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-fe5341bd .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-fe5341bd .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.uagb-block-4547cc99.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-4547cc99 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-4547cc99 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-4547cc99 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-4547cc99 .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-4547cc99 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.uagb-block-5cc8c098.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-5cc8c098 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-5cc8c098 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-5cc8c098 .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-5cc8c098 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:237163:\"document.addEventListener(\"DOMContentLoaded\", function(){ \t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\t\tconst scope = document.querySelector( '.uagb-block-fe5341bd' );\n\t\t\t\t\tif ( scope ){\n\t\t\t\t\t\tif ( scope.children[0].classList.contains( 'spectra-image-gallery__layout--isogrid' ) ) {\n\t\t\t\t\t\t\tsetTimeout( function() {\n\t\t\t\t\t\t\t\tconst element = scope.querySelector( '.spectra-image-gallery__layout--isogrid' );\n\t\t\t\t\t\t\t\tconst isotope = new Isotope( element, {\n\t\t\t\t\t\t\t\t\titemSelector: '.spectra-image-gallery__media-wrapper--isotope',\n\t\t\t\t\t\t\t\t\tlayoutMode: 'fitRows',\n\t\t\t\t\t\t\t\t} );\n\t\t\t\t\t\t\t\timagesLoaded( element ).on( 'progress', function() {\n\t\t\t\t\t\t\t\t\tisotope.layout();\n\t\t\t\t\t\t\t\t});\n\t\t\t\t\t\t\t\tUAGBImageGalleryMasonry.initByOffset( element, isotope );\n\t\t\t\t\t\t\t}, 500 );\n\t\t\t\t\t\t}\n\t\t\t\t\t\tUAGBImageGalleryPagedGrid.init( {\"block_id\":\"fe5341bd\",\"classMigrate\":true,\"readyToRender\":true,\"mediaGallery\":[{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":865,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_1.jpg\",\"alt\":\"Eco Wall - Estepona\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_estepona_1\/\",\"caption\":\"Eco Wall - Estepona\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":867,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_2.jpg\",\"alt\":\"Eco Wall - Los Flamingos\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_los_flamingos_2\/\",\"caption\":\"Eco Wall - Los Flamingos\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":169,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen-300x169.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":576,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen-1024x576.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen.jpg\",\"height\":1080,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":869,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen.jpg\",\"alt\":\"Eco Wall - Finca Oju00e9n\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_finca_ojen\/\",\"caption\":\"Eco Wall - Finca Oju00e9n\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_quinta-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":169,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_quinta-300x169.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":576,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_quinta-1024x576.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_quinta.jpg\",\"height\":1080,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":871,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_quinta.jpg\",\"alt\":\"Eco Wall - La Quinta\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_quinta\/\",\"caption\":\"Eco Wall - La Quinta\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":169,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_1-300x169.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":576,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_1-1024x576.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_1.jpg\",\"height\":1080,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":873,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_1.jpg\",\"alt\":\"Eco Wall - Granada FC\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_granada_club_futbol_1\/\",\"caption\":\"Eco Wall - Granada FC\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":875,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona_1.jpg\",\"alt\":\"Eco Wall - Estepona Hospital\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_hospital_estepona_1\/\",\"caption\":\"Eco Wall - Estepona Hospital\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_marbella_hill_club-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_marbella_hill_club-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_marbella_hill_club-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_marbella_hill_club.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":877,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_marbella_hill_club.jpg\",\"alt\":\"Eco Wall - Marbella Hill Club\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_marbella_hill_club\/\",\"caption\":\"Eco Wall - Marbella Hill Club\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_F26-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_F26-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_F26-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_F26.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":879,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_F26.jpg\",\"alt\":\"Eco Wall - Monte Mayor\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_monte_mayor_f26\/\",\"caption\":\"Eco Wall - Monte Mayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":881,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_1.jpg\",\"alt\":\"Eco Wall - Finca Oju00e9n\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_finca_ojen_1\/\",\"caption\":\"Eco Wall - Finca Oju00e9n\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":883,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_2.jpg\",\"alt\":\"Eco Wall - La Zagaleta\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_a2-32_2\/\",\"caption\":\"Eco Wall - La Zagaleta\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":885,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_estepona\/\",\"caption\":\"Eco Wall - Estepona\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":169,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_2-300x169.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":576,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_2-1024x576.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_2.jpg\",\"height\":1080,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":887,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_granada_club_futbol_2\/\",\"caption\":\"Eco Wall - Granada FC\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":889,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_a2_29_1\/\",\"caption\":\"Eco Wall - La Zagaleta A2\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":891,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_a2-32\/\",\"caption\":\"Eco Wall - La Zagaleta A2\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":893,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_cementerio_arcos_frontera\/\",\"caption\":\"Eco Wall - Arcos de la Frontera Cemetery\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":895,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_finca_ojen_2\/\",\"caption\":\"Eco Wall - Finca Oju00e9n\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":169,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol-300x169.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":576,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol-1024x576.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol.jpg\",\"height\":1080,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":897,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_granada_club_futbol\/\",\"caption\":\"Eco Wall - Granada FC\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":899,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_cementerio_arcos_frontera_1\/\",\"caption\":\"Eco Wall - Arcos de la Frontera Cemetery\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":901,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_a2-32_1\/\",\"caption\":\"Eco Wall - La Zagaleta\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":903,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_h24\/\",\"caption\":\"Eco Wall - La Zagaleta\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":905,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_3.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_los_flamingos_3\/\",\"caption\":\"Eco Wall - Los Flamingos\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_mijas-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_mijas-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_mijas-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_mijas.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":907,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_mijas.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_mijas\/\",\"caption\":\"Eco Wall - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":909,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_h24_2\/\",\"caption\":\"Eco Wall - La Zagaleta\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":911,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_monte_mayor_g22_1\/\",\"caption\":\"Eco Wall - Montemayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":913,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_monte_mayor_g22_2\/\",\"caption\":\"Eco Wall - Montemayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benahavis-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benahavis-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benahavis-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benahavis.jpg\",\"height\":1536,\"width\":2048,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":915,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benahavis.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_benahavis\/\",\"caption\":\"Eco Wall - Benahavis\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":917,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_hospital_estepona\/\",\"caption\":\"Eco Wall -  Estepona Hospital\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":919,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_h24_1\/\",\"caption\":\"Eco Wall - La Zagaleta\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_01-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_01-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_01-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_01.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":921,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_01.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_los_flamingos_01\/\",\"caption\":\"Eco Wall - Los Flamingos\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benidorm-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benidorm-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benidorm-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benidorm.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":923,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benidorm.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_benidorm\/\",\"caption\":\"Eco Wall - Benidorm\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":925,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_estepona_2\/\",\"caption\":\"Eco Wall - Estepona\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":927,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_los_flamingos\/\",\"caption\":\"Eco Wall - Los Flamingos\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":929,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_3.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_finca_ojen_3\/\",\"caption\":\"Eco Wall - Finca Oju00e9n\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":931,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_a2_29\/\",\"caption\":\"Eco Wall - La Zagaleta\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_A6-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_A6-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_A6-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_A6.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":933,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_A6.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_monte_mayor_a6\/\",\"caption\":\"Eco Wall - Montemayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":935,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_monte_mayor_g22\/\",\"caption\":\"Eco Wall - Montemayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":170,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja_1-300x170.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":579,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja_1-1024x579.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja_1.jpg\",\"height\":760,\"width\":1344,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":937,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_nerja_1\/\",\"caption\":\"Eco Wall - Nerja\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":170,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja-300x170.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":579,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja-1024x579.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja.jpg\",\"height\":760,\"width\":1344,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":939,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_nerja\/\",\"caption\":\"Eco Wall - Nerja\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":941,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_parque_algaidas_1\/\",\"caption\":\"Eco Wall - Algaidas Park\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":943,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_3.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_parque_algaidas_3\/\",\"caption\":\"Eco Wall - Algaidas Park\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":945,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_parque_algaidas\/\",\"caption\":\"Eco Wall - Algaidas Park\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":947,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_poligono_casares_1\/\",\"caption\":\"Eco Wall - Casares Industrial Area\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":949,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_poligono_casares\/\",\"caption\":\"Eco Wall - Casares Industrial Area\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":951,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_sotogrande_cadiz_1\/\",\"caption\":\"Eco Wall - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":953,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_sotogrande_cadiz_2\/\",\"caption\":\"Eco Wall - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":955,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_sotogrande_cadiz\/\",\"caption\":\"Eco Wall - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_tavira_portugal-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_tavira_portugal-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_tavira_portugal-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_tavira_portugal.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":957,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_tavira_portugal.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_tavira_portugal\/\",\"caption\":\"Eco Wall - Tavira, Portugal\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":959,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_parque_algaidas_2\/\",\"caption\":\"Eco Wall - Parque Algaidas\"}],\"mediaIDs\":[865,867,869,871,873,875,877,879,881,883,885,887,889,891,893,895,897,899,901,903,905,907,909,911,913,915,917,919,921,923,925,927,929,931,933,935,937,939,941,943,945,947,949,951,953,955,957,959],\"imageClickEvent\":\"lightbox\",\"captionVisibility\":\"always\",\"imageCaptionAlignment\":\"bottom center\",\"imageCaptionAlignment01\":\"bottom\",\"gridPages\":8,\"feedPagination\":true,\"paginateLimit\":6,\"captionFontSize\":11,\"captionBackgroundEffectAmountHover\":100,\"captionBackgroundColor\":\"rgba(0,0,0,0.3)\",\"paginateDotDistance\":25,\"paginateColor\":\"var(--ast-global-color-0)\",\"paginateColorHover\":\"\",\"imageBoxShadowColor\":\"\",\"tileSize\":0,\"focusList\":[],\"focusListObject\":[],\"feedLayout\":\"grid\",\"imageDisplayCaption\":true,\"galleryImageSize\":\"large\",\"galleryImageSizeTablet\":\"large\",\"galleryImageSizeMobile\":\"medium\",\"disableLazyLoad\":false,\"lightboxDisplayCaptions\":false,\"lightboxThumbnails\":false,\"lightboxDisplayCount\":false,\"lightboxCloseIcon\":\"xmark\",\"lightboxCaptionHeight\":50,\"lightboxCaptionHeightTablet\":\"\",\"lightboxCaptionHeightMobile\":\"\",\"lightboxIconSize\":24,\"lightboxIconSizeTablet\":\"\",\"lightboxIconSizeMobile\":\"\",\"captionDisplayType\":\"overlay\",\"imageCaptionAlignment02\":\"center\",\"imageDefaultCaption\":\"No Caption\",\"captionPaddingTop\":8,\"captionPaddingRight\":8,\"captionPaddingBottom\":8,\"captionPaddingLeft\":8,\"captionPaddingTopTab\":8,\"captionPaddingRightTab\":8,\"captionPaddingBottomTab\":8,\"captionPaddingLeftTab\":8,\"captionPaddingTopMob\":8,\"captionPaddingRightMob\":8,\"captionPaddingBottomMob\":8,\"captionPaddingLeftMob\":8,\"captionPaddingUnit\":\"px\",\"captionPaddingUnitTab\":\"px\",\"captionPaddingUnitMob\":\"px\",\"captionPaddingUnitLink\":true,\"captionGap\":0,\"captionGapUnit\":\"px\",\"columnsDesk\":3,\"columnsTab\":3,\"columnsMob\":2,\"gridImageGap\":8,\"gridImageGapTab\":\"\",\"gridImageGapMob\":\"\",\"gridImageGapUnit\":\"px\",\"gridImageGapUnitTab\":\"px\",\"gridImageGapUnitMob\":\"px\",\"feedMarginTop\":\"\",\"feedMarginRight\":\"\",\"feedMarginBottom\":\"\",\"feedMarginLeft\":\"\",\"feedMarginTopTab\":\"\",\"feedMarginRightTab\":\"\",\"feedMarginBottomTab\":\"\",\"feedMarginLeftTab\":\"\",\"feedMarginTopMob\":\"\",\"feedMarginRightMob\":\"\",\"feedMarginBottomMob\":\"\",\"feedMarginLeftMob\":\"\",\"feedMarginUnit\":\"px\",\"feedMarginUnitTab\":\"px\",\"feedMarginUnitMob\":\"px\",\"feedMarginUnitLink\":true,\"carouselStartAt\":0,\"carouselSquares\":false,\"carouselLoop\":true,\"carouselAutoplay\":true,\"carouselAutoplaySpeed\":2000,\"carouselPauseOnHover\":true,\"carouselTransitionSpeed\":500,\"gridPageNumber\":1,\"paginateUseArrows\":true,\"paginateUseDots\":true,\"paginateUseLoader\":true,\"paginateButtonAlign\":\"center\",\"paginateButtonText\":\"Load More Images\",\"paginateButtonPaddingTop\":\"\",\"paginateButtonPaddingRight\":\"\",\"paginateButtonPaddingBottom\":\"\",\"paginateButtonPaddingLeft\":\"\",\"paginateButtonPaddingTopTab\":\"\",\"paginateButtonPaddingRightTab\":\"\",\"paginateButtonPaddingBottomTab\":\"\",\"paginateButtonPaddingLeftTab\":\"\",\"paginateButtonPaddingTopMob\":\"\",\"paginateButtonPaddingRightMob\":\"\",\"paginateButtonPaddingBottomMob\":\"\",\"paginateButtonPaddingLeftMob\":\"\",\"paginateButtonPaddingUnit\":\"px\",\"paginateButtonPaddingUnitTab\":\"px\",\"paginateButtonPaddingUnitMob\":\"px\",\"paginateButtonPaddingUnitLink\":true,\"imageEnableZoom\":true,\"imageZoomType\":\"zoom-in\",\"captionBackgroundEnableBlur\":false,\"captionBackgroundBlurAmount\":0,\"captionBackgroundBlurAmountHover\":5,\"lightboxEdgeDistance\":10,\"lightboxEdgeDistanceTablet\":\"\",\"lightboxEdgeDistanceMobile\":\"\",\"lightboxBackgroundEnableBlur\":true,\"lightboxBackgroundBlurAmount\":5,\"lightboxBackgroundColor\":\"rgba(0,0,0,0.75)\",\"lightboxIconColor\":\"rgba(255,255,255,1)\",\"lightboxCaptionColor\":\"rgba(255,255,255,1)\",\"lightboxCaptionBackgroundColor\":\"rgba(0,0,0,1)\",\"captionLoadGoogleFonts\":false,\"captionFontFamily\":\"Default\",\"captionFontWeight\":\"\",\"captionFontStyle\":\"normal\",\"captionTransform\":\"\",\"captionDecoration\":\"none\",\"captionFontSizeType\":\"px\",\"captionFontSizeTab\":\"\",\"captionFontSizeMob\":\"\",\"captionLineHeightType\":\"em\",\"captionLineHeight\":\"\",\"captionLineHeightTab\":\"\",\"captionLineHeightMob\":\"\",\"loadMoreLoadGoogleFonts\":false,\"loadMoreFontFamily\":\"Default\",\"loadMoreFontWeight\":\"\",\"loadMoreFontStyle\":\"normal\",\"loadMoreTransform\":\"\",\"loadMoreDecoration\":\"none\",\"loadMoreFontSizeType\":\"px\",\"loadMoreFontSize\":\"\",\"loadMoreFontSizeTab\":\"\",\"loadMoreFontSizeMob\":\"\",\"loadMoreLineHeightType\":\"em\",\"loadMoreLineHeight\":\"\",\"loadMoreLineHeightTab\":\"\",\"loadMoreLineHeightMob\":\"\",\"lightboxLoadGoogleFonts\":false,\"lightboxFontFamily\":\"Default\",\"lightboxFontWeight\":\"\",\"lightboxFontStyle\":\"normal\",\"lightboxTransform\":\"\",\"lightboxDecoration\":\"none\",\"lightboxFontSizeType\":\"px\",\"lightboxFontSize\":\"\",\"lightboxFontSizeTab\":\"\",\"lightboxFontSizeMob\":\"\",\"lightboxLineHeightType\":\"em\",\"lightboxLineHeight\":\"\",\"lightboxLineHeightTab\":\"\",\"lightboxLineHeightMob\":\"\",\"captionBackgroundEffect\":\"none\",\"captionBackgroundEffectHover\":\"none\",\"captionBackgroundEffectAmount\":100,\"captionColor\":\"rgba(255,255,255,1)\",\"captionColorHover\":\"rgba(255,255,255,1)\",\"captionBackgroundColorHover\":\"rgba(0,0,0,0.75)\",\"overlayColor\":\"rgba(0,0,0,0)\",\"overlayColorHover\":\"rgba(0,0,0,0)\",\"captionSeparateColors\":false,\"paginateArrowDistance\":-24,\"paginateArrowDistanceUnit\":\"px\",\"paginateArrowSize\":24,\"paginateDotDistanceUnit\":\"px\",\"paginateLoaderSize\":18,\"paginateButtonTextColor\":\"\",\"paginateButtonTextColorHover\":\"\",\"imageBoxShadowHOffset\":0,\"imageBoxShadowVOffset\":0,\"imageBoxShadowBlur\":\"\",\"imageBoxShadowSpread\":\"\",\"imageBoxShadowPosition\":\"outset\",\"imageBoxShadowColorHover\":\"\",\"imageBoxShadowHOffsetHover\":0,\"imageBoxShadowVOffsetHover\":0,\"imageBoxShadowBlurHover\":\"\",\"imageBoxShadowSpreadHover\":\"\",\"imageBoxShadowPositionHover\":\"outset\",\"arrowBorderTopWidth\":4,\"arrowBorderLeftWidth\":4,\"arrowBorderRightWidth\":4,\"arrowBorderBottomWidth\":4,\"arrowBorderTopLeftRadius\":50,\"arrowBorderTopRightRadius\":50,\"arrowBorderBottomLeftRadius\":50,\"arrowBorderBottomRightRadius\":50,\"arrowBorderRadiusUnit\":\"px\",\"arrowBorderTopWidthTablet\":\"\",\"arrowBorderLeftWidthTablet\":\"\",\"arrowBorderRightWidthTablet\":\"\",\"arrowBorderBottomWidthTablet\":\"\",\"arrowBorderTopLeftRadiusTablet\":\"\",\"arrowBorderTopRightRadiusTablet\":\"\",\"arrowBorderBottomLeftRadiusTablet\":\"\",\"arrowBorderBottomRightRadiusTablet\":\"\",\"arrowBorderRadiusUnitTablet\":\"px\",\"arrowBorderTopWidthMobile\":\"\",\"arrowBorderLeftWidthMobile\":\"\",\"arrowBorderRightWidthMobile\":\"\",\"arrowBorderBottomWidthMobile\":\"\",\"arrowBorderTopLeftRadiusMobile\":\"\",\"arrowBorderTopRightRadiusMobile\":\"\",\"arrowBorderBottomLeftRadiusMobile\":\"\",\"arrowBorderBottomRightRadiusMobile\":\"\",\"arrowBorderRadiusUnitMobile\":\"px\",\"arrowBorderStyle\":\"none\",\"arrowBorderColor\":\"\",\"arrowBorderHColor\":\"\",\"btnBorderTopWidth\":\"\",\"btnBorderLeftWidth\":\"\",\"btnBorderRightWidth\":\"\",\"btnBorderBottomWidth\":\"\",\"btnBorderTopLeftRadius\":\"\",\"btnBorderTopRightRadius\":\"\",\"btnBorderBottomLeftRadius\":\"\",\"btnBorderBottomRightRadius\":\"\",\"btnBorderRadiusUnit\":\"px\",\"btnBorderTopWidthTablet\":\"\",\"btnBorderLeftWidthTablet\":\"\",\"btnBorderRightWidthTablet\":\"\",\"btnBorderBottomWidthTablet\":\"\",\"btnBorderTopLeftRadiusTablet\":\"\",\"btnBorderTopRightRadiusTablet\":\"\",\"btnBorderBottomLeftRadiusTablet\":\"\",\"btnBorderBottomRightRadiusTablet\":\"\",\"btnBorderRadiusUnitTablet\":\"px\",\"btnBorderTopWidthMobile\":\"\",\"btnBorderLeftWidthMobile\":\"\",\"btnBorderRightWidthMobile\":\"\",\"btnBorderBottomWidthMobile\":\"\",\"btnBorderTopLeftRadiusMobile\":\"\",\"btnBorderTopRightRadiusMobile\":\"\",\"btnBorderBottomLeftRadiusMobile\":\"\",\"btnBorderBottomRightRadiusMobile\":\"\",\"btnBorderRadiusUnitMobile\":\"px\",\"btnBorderStyle\":\"\",\"btnBorderColor\":\"\",\"btnBorderHColor\":\"\",\"imageBorderTopWidth\":\"\",\"imageBorderLeftWidth\":\"\",\"imageBorderRightWidth\":\"\",\"imageBorderBottomWidth\":\"\",\"imageBorderTopLeftRadius\":\"\",\"imageBorderTopRightRadius\":\"\",\"imageBorderBottomLeftRadius\":\"\",\"imageBorderBottomRightRadius\":\"\",\"imageBorderRadiusUnit\":\"px\",\"imageBorderTopWidthTablet\":\"\",\"imageBorderLeftWidthTablet\":\"\",\"imageBorderRightWidthTablet\":\"\",\"imageBorderBottomWidthTablet\":\"\",\"imageBorderTopLeftRadiusTablet\":\"\",\"imageBorderTopRightRadiusTablet\":\"\",\"imageBorderBottomLeftRadiusTablet\":\"\",\"imageBorderBottomRightRadiusTablet\":\"\",\"imageBorderRadiusUnitTablet\":\"px\",\"imageBorderTopWidthMobile\":\"\",\"imageBorderLeftWidthMobile\":\"\",\"imageBorderRightWidthMobile\":\"\",\"imageBorderBottomWidthMobile\":\"\",\"imageBorderTopLeftRadiusMobile\":\"\",\"imageBorderTopRightRadiusMobile\":\"\",\"imageBorderBottomLeftRadiusMobile\":\"\",\"imageBorderBottomRightRadiusMobile\":\"\",\"imageBorderRadiusUnitMobile\":\"px\",\"imageBorderStyle\":\"\",\"imageBorderColor\":\"\",\"imageBorderHColor\":\"\",\"mainTitleBorderTopWidth\":2,\"mainTitleBorderLeftWidth\":0,\"mainTitleBorderRightWidth\":0,\"mainTitleBorderBottomWidth\":2,\"mainTitleBorderTopLeftRadius\":\"\",\"mainTitleBorderTopRightRadius\":\"\",\"mainTitleBorderBottomLeftRadius\":\"\",\"mainTitleBorderBottomRightRadius\":\"\",\"mainTitleBorderRadiusUnit\":\"px\",\"mainTitleBorderTopWidthTablet\":\"\",\"mainTitleBorderLeftWidthTablet\":\"\",\"mainTitleBorderRightWidthTablet\":\"\",\"mainTitleBorderBottomWidthTablet\":\"\",\"mainTitleBorderTopLeftRadiusTablet\":\"\",\"mainTitleBorderTopRightRadiusTablet\":\"\",\"mainTitleBorderBottomLeftRadiusTablet\":\"\",\"mainTitleBorderBottomRightRadiusTablet\":\"\",\"mainTitleBorderRadiusUnitTablet\":\"px\",\"mainTitleBorderTopWidthMobile\":\"\",\"mainTitleBorderLeftWidthMobile\":\"\",\"mainTitleBorderRightWidthMobile\":\"\",\"mainTitleBorderBottomWidthMobile\":\"\",\"mainTitleBorderTopLeftRadiusMobile\":\"\",\"mainTitleBorderTopRightRadiusMobile\":\"\",\"mainTitleBorderBottomLeftRadiusMobile\":\"\",\"mainTitleBorderBottomRightRadiusMobile\":\"\",\"mainTitleBorderRadiusUnitMobile\":\"px\",\"mainTitleBorderStyle\":\"\",\"mainTitleBorderColor\":\"\",\"mainTitleBorderHColor\":\"\"}, '.uagb-block-fe5341bd', {\"lazy\":true,\"slidesPerView\":1,\"navigation\":{\"nextEl\":\".uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .swiper-button-next\",\"prevEl\":\".uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .swiper-button-prev\"},\"keyboard\":{\"enabled\":true}}, [] );\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', () => {\n\t\t\t\t\tconst blockScope = document.querySelector( '.uagb-block-fe5341bd' );\n\t\t\t\t\tif ( ! blockScope ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\t\t\t\t\t\tblockScope.addEventListener('keydown', (event) => {\n\t\t\t\t\t\tif ( 13 === event.keyCode || 32 === event.keyCode ) {\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tblockScope.click();\n\t\t\t\t\t\t}\n\t\t\t\t\t} );\n\n\t\t\t\t\tlet lightboxSwiper = null;\n\t\t\t\t\tlet thumbnailSwiper = null;\n\n\t\t\t\t\t\t\t\t\t\tlet lightboxSettings = {\"lazy\":true,\"slidesPerView\":1,\"navigation\":{\"nextEl\":\".uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .swiper-button-next\",\"prevEl\":\".uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .swiper-button-prev\"},\"keyboard\":{\"enabled\":true}};\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tlightboxSwiper = new Swiper( \".uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main\",\n\t\t\t\t\t\t{\"lazy\":true,\"slidesPerView\":1,\"navigation\":{\"nextEl\":\".uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .swiper-button-next\",\"prevEl\":\".uagb-block-fe5341bd+.spectra-image-gallery__control-lightbox .swiper-button-prev\"},\"keyboard\":{\"enabled\":true}}\t\t\t\t\t);\n\t\t\t\t\tloadLightBoxImages( blockScope, lightboxSwiper, null, {\"block_id\":\"fe5341bd\",\"classMigrate\":true,\"readyToRender\":true,\"mediaGallery\":[{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":865,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_1.jpg\",\"alt\":\"Eco Wall - Estepona\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_estepona_1\/\",\"caption\":\"Eco Wall - Estepona\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":867,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_2.jpg\",\"alt\":\"Eco Wall - Los Flamingos\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_los_flamingos_2\/\",\"caption\":\"Eco Wall - Los Flamingos\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":169,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen-300x169.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":576,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen-1024x576.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen.jpg\",\"height\":1080,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":869,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen.jpg\",\"alt\":\"Eco Wall - Finca Oju00e9n\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_finca_ojen\/\",\"caption\":\"Eco Wall - Finca Oju00e9n\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_quinta-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":169,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_quinta-300x169.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":576,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_quinta-1024x576.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_quinta.jpg\",\"height\":1080,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":871,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_quinta.jpg\",\"alt\":\"Eco Wall - La Quinta\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_quinta\/\",\"caption\":\"Eco Wall - La Quinta\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":169,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_1-300x169.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":576,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_1-1024x576.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_1.jpg\",\"height\":1080,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":873,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_1.jpg\",\"alt\":\"Eco Wall - Granada FC\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_granada_club_futbol_1\/\",\"caption\":\"Eco Wall - Granada FC\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":875,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona_1.jpg\",\"alt\":\"Eco Wall - Estepona Hospital\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_hospital_estepona_1\/\",\"caption\":\"Eco Wall - Estepona Hospital\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_marbella_hill_club-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_marbella_hill_club-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_marbella_hill_club-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_marbella_hill_club.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":877,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_marbella_hill_club.jpg\",\"alt\":\"Eco Wall - Marbella Hill Club\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_marbella_hill_club\/\",\"caption\":\"Eco Wall - Marbella Hill Club\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_F26-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_F26-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_F26-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_F26.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":879,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_F26.jpg\",\"alt\":\"Eco Wall - Monte Mayor\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_monte_mayor_f26\/\",\"caption\":\"Eco Wall - Monte Mayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":881,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_1.jpg\",\"alt\":\"Eco Wall - Finca Oju00e9n\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_finca_ojen_1\/\",\"caption\":\"Eco Wall - Finca Oju00e9n\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":883,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_2.jpg\",\"alt\":\"Eco Wall - La Zagaleta\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_a2-32_2\/\",\"caption\":\"Eco Wall - La Zagaleta\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":885,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_estepona\/\",\"caption\":\"Eco Wall - Estepona\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":169,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_2-300x169.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":576,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_2-1024x576.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_2.jpg\",\"height\":1080,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":887,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_granada_club_futbol_2\/\",\"caption\":\"Eco Wall - Granada FC\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":889,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_a2_29_1\/\",\"caption\":\"Eco Wall - La Zagaleta A2\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":891,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_a2-32\/\",\"caption\":\"Eco Wall - La Zagaleta A2\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":893,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_cementerio_arcos_frontera\/\",\"caption\":\"Eco Wall - Arcos de la Frontera Cemetery\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":895,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_finca_ojen_2\/\",\"caption\":\"Eco Wall - Finca Oju00e9n\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":169,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol-300x169.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":576,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol-1024x576.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol.jpg\",\"height\":1080,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":897,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_granada_club_futbol.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_granada_club_futbol\/\",\"caption\":\"Eco Wall - Granada FC\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":899,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_cementerio_arcos_frontera_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_cementerio_arcos_frontera_1\/\",\"caption\":\"Eco Wall - Arcos de la Frontera Cemetery\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":901,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2-32_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_a2-32_1\/\",\"caption\":\"Eco Wall - La Zagaleta\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":903,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_h24\/\",\"caption\":\"Eco Wall - La Zagaleta\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":905,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_3.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_los_flamingos_3\/\",\"caption\":\"Eco Wall - Los Flamingos\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_mijas-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_mijas-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_mijas-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_mijas.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":907,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_mijas.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_mijas\/\",\"caption\":\"Eco Wall - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":909,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_h24_2\/\",\"caption\":\"Eco Wall - La Zagaleta\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":911,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_monte_mayor_g22_1\/\",\"caption\":\"Eco Wall - Montemayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":913,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_monte_mayor_g22_2\/\",\"caption\":\"Eco Wall - Montemayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benahavis-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benahavis-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benahavis-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benahavis.jpg\",\"height\":1536,\"width\":2048,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":915,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benahavis.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_benahavis\/\",\"caption\":\"Eco Wall - Benahavis\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":917,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_hospital_estepona.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_hospital_estepona\/\",\"caption\":\"Eco Wall -  Estepona Hospital\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":919,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_H24_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_h24_1\/\",\"caption\":\"Eco Wall - La Zagaleta\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_01-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_01-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_01-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_01.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":921,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos_01.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_los_flamingos_01\/\",\"caption\":\"Eco Wall - Los Flamingos\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benidorm-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benidorm-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benidorm-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benidorm.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":923,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_benidorm.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_benidorm\/\",\"caption\":\"Eco Wall - Benidorm\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":925,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_estepona_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_estepona_2\/\",\"caption\":\"Eco Wall - Estepona\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":927,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_los_flamingos.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_los_flamingos\/\",\"caption\":\"Eco Wall - Los Flamingos\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":929,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_finca_ojen_3.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_finca_ojen_3\/\",\"caption\":\"Eco Wall - Finca Oju00e9n\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":931,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_la_zagaleta_A2_29.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_la_zagaleta_a2_29\/\",\"caption\":\"Eco Wall - La Zagaleta\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_A6-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_A6-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_A6-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_A6.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":933,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_A6.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_monte_mayor_a6\/\",\"caption\":\"Eco Wall - Montemayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":935,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_monte_mayor_G22.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_monte_mayor_g22\/\",\"caption\":\"Eco Wall - Montemayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":170,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja_1-300x170.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":579,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja_1-1024x579.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja_1.jpg\",\"height\":760,\"width\":1344,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":937,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_nerja_1\/\",\"caption\":\"Eco Wall - Nerja\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":170,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja-300x170.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":579,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja-1024x579.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja.jpg\",\"height\":760,\"width\":1344,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":939,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_nerja.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_nerja\/\",\"caption\":\"Eco Wall - Nerja\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":941,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_parque_algaidas_1\/\",\"caption\":\"Eco Wall - Algaidas Park\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":943,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_3.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_parque_algaidas_3\/\",\"caption\":\"Eco Wall - Algaidas Park\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":945,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_parque_algaidas\/\",\"caption\":\"Eco Wall - Algaidas Park\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":947,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_poligono_casares_1\/\",\"caption\":\"Eco Wall - Casares Industrial Area\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":949,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_poligono_casares.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_poligono_casares\/\",\"caption\":\"Eco Wall - Casares Industrial Area\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":951,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_sotogrande_cadiz_1\/\",\"caption\":\"Eco Wall - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":953,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_sotogrande_cadiz_2\/\",\"caption\":\"Eco Wall - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":955,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_sotogrande_cadiz.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_sotogrande_cadiz\/\",\"caption\":\"Eco Wall - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_tavira_portugal-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_tavira_portugal-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_tavira_portugal-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_tavira_portugal.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":957,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_tavira_portugal.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_tavira_portugal\/\",\"caption\":\"Eco Wall - Tavira, Portugal\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":959,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_ecologico_parque_algaidas_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_ecologico_parque_algaidas_2\/\",\"caption\":\"Eco Wall - Parque Algaidas\"}],\"mediaIDs\":[865,867,869,871,873,875,877,879,881,883,885,887,889,891,893,895,897,899,901,903,905,907,909,911,913,915,917,919,921,923,925,927,929,931,933,935,937,939,941,943,945,947,949,951,953,955,957,959],\"imageClickEvent\":\"lightbox\",\"captionVisibility\":\"always\",\"imageCaptionAlignment\":\"bottom center\",\"imageCaptionAlignment01\":\"bottom\",\"gridPages\":8,\"feedPagination\":true,\"paginateLimit\":6,\"captionFontSize\":11,\"captionBackgroundEffectAmountHover\":100,\"captionBackgroundColor\":\"rgba(0,0,0,0.3)\",\"paginateDotDistance\":25,\"paginateColor\":\"var(--ast-global-color-0)\",\"paginateColorHover\":\"\",\"imageBoxShadowColor\":\"\",\"tileSize\":0,\"focusList\":[],\"focusListObject\":[],\"feedLayout\":\"grid\",\"imageDisplayCaption\":true,\"galleryImageSize\":\"large\",\"galleryImageSizeTablet\":\"large\",\"galleryImageSizeMobile\":\"medium\",\"disableLazyLoad\":false,\"lightboxDisplayCaptions\":false,\"lightboxThumbnails\":false,\"lightboxDisplayCount\":false,\"lightboxCloseIcon\":\"xmark\",\"lightboxCaptionHeight\":50,\"lightboxCaptionHeightTablet\":\"\",\"lightboxCaptionHeightMobile\":\"\",\"lightboxIconSize\":24,\"lightboxIconSizeTablet\":\"\",\"lightboxIconSizeMobile\":\"\",\"captionDisplayType\":\"overlay\",\"imageCaptionAlignment02\":\"center\",\"imageDefaultCaption\":\"No Caption\",\"captionPaddingTop\":8,\"captionPaddingRight\":8,\"captionPaddingBottom\":8,\"captionPaddingLeft\":8,\"captionPaddingTopTab\":8,\"captionPaddingRightTab\":8,\"captionPaddingBottomTab\":8,\"captionPaddingLeftTab\":8,\"captionPaddingTopMob\":8,\"captionPaddingRightMob\":8,\"captionPaddingBottomMob\":8,\"captionPaddingLeftMob\":8,\"captionPaddingUnit\":\"px\",\"captionPaddingUnitTab\":\"px\",\"captionPaddingUnitMob\":\"px\",\"captionPaddingUnitLink\":true,\"captionGap\":0,\"captionGapUnit\":\"px\",\"columnsDesk\":3,\"columnsTab\":3,\"columnsMob\":2,\"gridImageGap\":8,\"gridImageGapTab\":\"\",\"gridImageGapMob\":\"\",\"gridImageGapUnit\":\"px\",\"gridImageGapUnitTab\":\"px\",\"gridImageGapUnitMob\":\"px\",\"feedMarginTop\":\"\",\"feedMarginRight\":\"\",\"feedMarginBottom\":\"\",\"feedMarginLeft\":\"\",\"feedMarginTopTab\":\"\",\"feedMarginRightTab\":\"\",\"feedMarginBottomTab\":\"\",\"feedMarginLeftTab\":\"\",\"feedMarginTopMob\":\"\",\"feedMarginRightMob\":\"\",\"feedMarginBottomMob\":\"\",\"feedMarginLeftMob\":\"\",\"feedMarginUnit\":\"px\",\"feedMarginUnitTab\":\"px\",\"feedMarginUnitMob\":\"px\",\"feedMarginUnitLink\":true,\"carouselStartAt\":0,\"carouselSquares\":false,\"carouselLoop\":true,\"carouselAutoplay\":true,\"carouselAutoplaySpeed\":2000,\"carouselPauseOnHover\":true,\"carouselTransitionSpeed\":500,\"gridPageNumber\":1,\"paginateUseArrows\":true,\"paginateUseDots\":true,\"paginateUseLoader\":true,\"paginateButtonAlign\":\"center\",\"paginateButtonText\":\"Load More Images\",\"paginateButtonPaddingTop\":\"\",\"paginateButtonPaddingRight\":\"\",\"paginateButtonPaddingBottom\":\"\",\"paginateButtonPaddingLeft\":\"\",\"paginateButtonPaddingTopTab\":\"\",\"paginateButtonPaddingRightTab\":\"\",\"paginateButtonPaddingBottomTab\":\"\",\"paginateButtonPaddingLeftTab\":\"\",\"paginateButtonPaddingTopMob\":\"\",\"paginateButtonPaddingRightMob\":\"\",\"paginateButtonPaddingBottomMob\":\"\",\"paginateButtonPaddingLeftMob\":\"\",\"paginateButtonPaddingUnit\":\"px\",\"paginateButtonPaddingUnitTab\":\"px\",\"paginateButtonPaddingUnitMob\":\"px\",\"paginateButtonPaddingUnitLink\":true,\"imageEnableZoom\":true,\"imageZoomType\":\"zoom-in\",\"captionBackgroundEnableBlur\":false,\"captionBackgroundBlurAmount\":0,\"captionBackgroundBlurAmountHover\":5,\"lightboxEdgeDistance\":10,\"lightboxEdgeDistanceTablet\":\"\",\"lightboxEdgeDistanceMobile\":\"\",\"lightboxBackgroundEnableBlur\":true,\"lightboxBackgroundBlurAmount\":5,\"lightboxBackgroundColor\":\"rgba(0,0,0,0.75)\",\"lightboxIconColor\":\"rgba(255,255,255,1)\",\"lightboxCaptionColor\":\"rgba(255,255,255,1)\",\"lightboxCaptionBackgroundColor\":\"rgba(0,0,0,1)\",\"captionLoadGoogleFonts\":false,\"captionFontFamily\":\"Default\",\"captionFontWeight\":\"\",\"captionFontStyle\":\"normal\",\"captionTransform\":\"\",\"captionDecoration\":\"none\",\"captionFontSizeType\":\"px\",\"captionFontSizeTab\":\"\",\"captionFontSizeMob\":\"\",\"captionLineHeightType\":\"em\",\"captionLineHeight\":\"\",\"captionLineHeightTab\":\"\",\"captionLineHeightMob\":\"\",\"loadMoreLoadGoogleFonts\":false,\"loadMoreFontFamily\":\"Default\",\"loadMoreFontWeight\":\"\",\"loadMoreFontStyle\":\"normal\",\"loadMoreTransform\":\"\",\"loadMoreDecoration\":\"none\",\"loadMoreFontSizeType\":\"px\",\"loadMoreFontSize\":\"\",\"loadMoreFontSizeTab\":\"\",\"loadMoreFontSizeMob\":\"\",\"loadMoreLineHeightType\":\"em\",\"loadMoreLineHeight\":\"\",\"loadMoreLineHeightTab\":\"\",\"loadMoreLineHeightMob\":\"\",\"lightboxLoadGoogleFonts\":false,\"lightboxFontFamily\":\"Default\",\"lightboxFontWeight\":\"\",\"lightboxFontStyle\":\"normal\",\"lightboxTransform\":\"\",\"lightboxDecoration\":\"none\",\"lightboxFontSizeType\":\"px\",\"lightboxFontSize\":\"\",\"lightboxFontSizeTab\":\"\",\"lightboxFontSizeMob\":\"\",\"lightboxLineHeightType\":\"em\",\"lightboxLineHeight\":\"\",\"lightboxLineHeightTab\":\"\",\"lightboxLineHeightMob\":\"\",\"captionBackgroundEffect\":\"none\",\"captionBackgroundEffectHover\":\"none\",\"captionBackgroundEffectAmount\":100,\"captionColor\":\"rgba(255,255,255,1)\",\"captionColorHover\":\"rgba(255,255,255,1)\",\"captionBackgroundColorHover\":\"rgba(0,0,0,0.75)\",\"overlayColor\":\"rgba(0,0,0,0)\",\"overlayColorHover\":\"rgba(0,0,0,0)\",\"captionSeparateColors\":false,\"paginateArrowDistance\":-24,\"paginateArrowDistanceUnit\":\"px\",\"paginateArrowSize\":24,\"paginateDotDistanceUnit\":\"px\",\"paginateLoaderSize\":18,\"paginateButtonTextColor\":\"\",\"paginateButtonTextColorHover\":\"\",\"imageBoxShadowHOffset\":0,\"imageBoxShadowVOffset\":0,\"imageBoxShadowBlur\":\"\",\"imageBoxShadowSpread\":\"\",\"imageBoxShadowPosition\":\"outset\",\"imageBoxShadowColorHover\":\"\",\"imageBoxShadowHOffsetHover\":0,\"imageBoxShadowVOffsetHover\":0,\"imageBoxShadowBlurHover\":\"\",\"imageBoxShadowSpreadHover\":\"\",\"imageBoxShadowPositionHover\":\"outset\",\"arrowBorderTopWidth\":4,\"arrowBorderLeftWidth\":4,\"arrowBorderRightWidth\":4,\"arrowBorderBottomWidth\":4,\"arrowBorderTopLeftRadius\":50,\"arrowBorderTopRightRadius\":50,\"arrowBorderBottomLeftRadius\":50,\"arrowBorderBottomRightRadius\":50,\"arrowBorderRadiusUnit\":\"px\",\"arrowBorderTopWidthTablet\":\"\",\"arrowBorderLeftWidthTablet\":\"\",\"arrowBorderRightWidthTablet\":\"\",\"arrowBorderBottomWidthTablet\":\"\",\"arrowBorderTopLeftRadiusTablet\":\"\",\"arrowBorderTopRightRadiusTablet\":\"\",\"arrowBorderBottomLeftRadiusTablet\":\"\",\"arrowBorderBottomRightRadiusTablet\":\"\",\"arrowBorderRadiusUnitTablet\":\"px\",\"arrowBorderTopWidthMobile\":\"\",\"arrowBorderLeftWidthMobile\":\"\",\"arrowBorderRightWidthMobile\":\"\",\"arrowBorderBottomWidthMobile\":\"\",\"arrowBorderTopLeftRadiusMobile\":\"\",\"arrowBorderTopRightRadiusMobile\":\"\",\"arrowBorderBottomLeftRadiusMobile\":\"\",\"arrowBorderBottomRightRadiusMobile\":\"\",\"arrowBorderRadiusUnitMobile\":\"px\",\"arrowBorderStyle\":\"none\",\"arrowBorderColor\":\"\",\"arrowBorderHColor\":\"\",\"btnBorderTopWidth\":\"\",\"btnBorderLeftWidth\":\"\",\"btnBorderRightWidth\":\"\",\"btnBorderBottomWidth\":\"\",\"btnBorderTopLeftRadius\":\"\",\"btnBorderTopRightRadius\":\"\",\"btnBorderBottomLeftRadius\":\"\",\"btnBorderBottomRightRadius\":\"\",\"btnBorderRadiusUnit\":\"px\",\"btnBorderTopWidthTablet\":\"\",\"btnBorderLeftWidthTablet\":\"\",\"btnBorderRightWidthTablet\":\"\",\"btnBorderBottomWidthTablet\":\"\",\"btnBorderTopLeftRadiusTablet\":\"\",\"btnBorderTopRightRadiusTablet\":\"\",\"btnBorderBottomLeftRadiusTablet\":\"\",\"btnBorderBottomRightRadiusTablet\":\"\",\"btnBorderRadiusUnitTablet\":\"px\",\"btnBorderTopWidthMobile\":\"\",\"btnBorderLeftWidthMobile\":\"\",\"btnBorderRightWidthMobile\":\"\",\"btnBorderBottomWidthMobile\":\"\",\"btnBorderTopLeftRadiusMobile\":\"\",\"btnBorderTopRightRadiusMobile\":\"\",\"btnBorderBottomLeftRadiusMobile\":\"\",\"btnBorderBottomRightRadiusMobile\":\"\",\"btnBorderRadiusUnitMobile\":\"px\",\"btnBorderStyle\":\"\",\"btnBorderColor\":\"\",\"btnBorderHColor\":\"\",\"imageBorderTopWidth\":\"\",\"imageBorderLeftWidth\":\"\",\"imageBorderRightWidth\":\"\",\"imageBorderBottomWidth\":\"\",\"imageBorderTopLeftRadius\":\"\",\"imageBorderTopRightRadius\":\"\",\"imageBorderBottomLeftRadius\":\"\",\"imageBorderBottomRightRadius\":\"\",\"imageBorderRadiusUnit\":\"px\",\"imageBorderTopWidthTablet\":\"\",\"imageBorderLeftWidthTablet\":\"\",\"imageBorderRightWidthTablet\":\"\",\"imageBorderBottomWidthTablet\":\"\",\"imageBorderTopLeftRadiusTablet\":\"\",\"imageBorderTopRightRadiusTablet\":\"\",\"imageBorderBottomLeftRadiusTablet\":\"\",\"imageBorderBottomRightRadiusTablet\":\"\",\"imageBorderRadiusUnitTablet\":\"px\",\"imageBorderTopWidthMobile\":\"\",\"imageBorderLeftWidthMobile\":\"\",\"imageBorderRightWidthMobile\":\"\",\"imageBorderBottomWidthMobile\":\"\",\"imageBorderTopLeftRadiusMobile\":\"\",\"imageBorderTopRightRadiusMobile\":\"\",\"imageBorderBottomLeftRadiusMobile\":\"\",\"imageBorderBottomRightRadiusMobile\":\"\",\"imageBorderRadiusUnitMobile\":\"px\",\"imageBorderStyle\":\"\",\"imageBorderColor\":\"\",\"imageBorderHColor\":\"\",\"mainTitleBorderTopWidth\":2,\"mainTitleBorderLeftWidth\":0,\"mainTitleBorderRightWidth\":0,\"mainTitleBorderBottomWidth\":2,\"mainTitleBorderTopLeftRadius\":\"\",\"mainTitleBorderTopRightRadius\":\"\",\"mainTitleBorderBottomLeftRadius\":\"\",\"mainTitleBorderBottomRightRadius\":\"\",\"mainTitleBorderRadiusUnit\":\"px\",\"mainTitleBorderTopWidthTablet\":\"\",\"mainTitleBorderLeftWidthTablet\":\"\",\"mainTitleBorderRightWidthTablet\":\"\",\"mainTitleBorderBottomWidthTablet\":\"\",\"mainTitleBorderTopLeftRadiusTablet\":\"\",\"mainTitleBorderTopRightRadiusTablet\":\"\",\"mainTitleBorderBottomLeftRadiusTablet\":\"\",\"mainTitleBorderBottomRightRadiusTablet\":\"\",\"mainTitleBorderRadiusUnitTablet\":\"px\",\"mainTitleBorderTopWidthMobile\":\"\",\"mainTitleBorderLeftWidthMobile\":\"\",\"mainTitleBorderRightWidthMobile\":\"\",\"mainTitleBorderBottomWidthMobile\":\"\",\"mainTitleBorderTopLeftRadiusMobile\":\"\",\"mainTitleBorderTopRightRadiusMobile\":\"\",\"mainTitleBorderBottomLeftRadiusMobile\":\"\",\"mainTitleBorderBottomRightRadiusMobile\":\"\",\"mainTitleBorderRadiusUnitMobile\":\"px\",\"mainTitleBorderStyle\":\"\",\"mainTitleBorderColor\":\"\",\"mainTitleBorderHColor\":\"\"}, thumbnailSwiper );\n\t\t\t\t\t\t\t\tconst regexCustomURL = new RegExp( '^((http|https):\/\/)(www.)?[a-zA-Z0-9@:%._\\+~#?&\/\/=\\-]{2,256}\\.[a-z]{2,6}\\b([-a-zA-Z0-9@:%._\\+~#?&\/\/=]*)$' );\n\t\t\tconst customLinks = {};\n\t\t\tconst customLinksBehaviour = {};\n\n\t\t\tconst getCustomURL = ( caption ) => {\n\t\t\t\tif ( ! customLinks ) {\n\t\t\t\t\treturn undefined;\n\t\t\t\t}\n\t\t\t\tconst imageID = parseInt( caption.getAttribute( 'data-spectra-gallery-image-id' ) );\n\t\t\t\treturn ( regexCustomURL.test( customLinks[ imageID ] ) ? customLinks[ imageID ] : undefined );\n\t\t\t}\n\n\t\t\tconst getCustomLinkBehaviour = (caption) => {\n\t\t\t\tif (!customLinksBehaviour) {\n\t\t\t\t\treturn true;\n\t\t\t\t}\n\t\t\t\tconst imageId = parseInt(caption.getAttribute('data-spectra-gallery-image-id'));\n\t\t\t\treturn !(customLinksBehaviour[imageId] === true);\n\t\t\t};\n\n\t\t\tconst captions = lightboxSwiper.el.querySelectorAll( '.spectra-image-gallery__control-lightbox--caption' );\n\t\t\tfor ( let i = 0; i < captions.length; i++ ) {\n\t\t\t\tconst customURL = getCustomURL( captions[ i ] );\n\t\t\t\tif ( customURL ) {\n\t\t\t\t\tconst anchor = document.createElement( 'a' );\n\t\t\t\t\tanchor.target = getCustomLinkBehaviour( captions[ i ] ) ? '_blank' : '_self';\n\t\t\t\t\tanchor.rel = 'noopener noreferrer';\n\t\t\t\t\tanchor.href = customURL;\n\t\t\t\t\tanchor.innerHTML = captions[ i ].innerHTML;\n\t\t\t\t\tcaptions[ i ].textContent = '';\n\t\t\t\t\tcaptions[ i ].appendChild( anchor );\n\t\t\t\t}\n\t\t\t}\n\t\t\t\t\t\t} );\n\t\t\tjQuery(document).ready(function(){if(window.matchMedia&&window.matchMedia(\"(hover:none)\").matches){jQuery(\".wp-block-uagb-image-gallery.uagb-block-fe5341bd\").addClass(\"spectra-touch-device\");}});\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\t\tconst scope = document.querySelector( '.uagb-block-4547cc99' );\n\t\t\t\t\tif ( scope ){\n\t\t\t\t\t\tif ( scope.children[0].classList.contains( 'spectra-image-gallery__layout--isogrid' ) ) {\n\t\t\t\t\t\t\tsetTimeout( function() {\n\t\t\t\t\t\t\t\tconst element = scope.querySelector( '.spectra-image-gallery__layout--isogrid' );\n\t\t\t\t\t\t\t\tconst isotope = new Isotope( element, {\n\t\t\t\t\t\t\t\t\titemSelector: '.spectra-image-gallery__media-wrapper--isotope',\n\t\t\t\t\t\t\t\t\tlayoutMode: 'fitRows',\n\t\t\t\t\t\t\t\t} );\n\t\t\t\t\t\t\t\timagesLoaded( element ).on( 'progress', function() {\n\t\t\t\t\t\t\t\t\tisotope.layout();\n\t\t\t\t\t\t\t\t});\n\t\t\t\t\t\t\t\tUAGBImageGalleryMasonry.initByOffset( element, isotope );\n\t\t\t\t\t\t\t}, 500 );\n\t\t\t\t\t\t}\n\t\t\t\t\t\tUAGBImageGalleryPagedGrid.init( {\"block_id\":\"4547cc99\",\"classMigrate\":true,\"readyToRender\":true,\"mediaGallery\":[{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":966,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sevilla_2\/\",\"caption\":\"Iron Grid - Sevilla\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_7-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_7-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_7-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_7.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":968,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_7.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_mijas_7\/\",\"caption\":\"Iron Grid - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_6-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_6-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_6-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_6.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":970,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_6.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_mijas_6\/\",\"caption\":\"Iron Grid - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_5-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_5-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_5-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_5.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":972,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_5.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_mijas_5\/\",\"caption\":\"Iron Grid - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_4-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_4-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_4-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_4.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":974,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_4.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_mijas_4\/\",\"caption\":\"Iron Grid - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":976,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_3.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_mijas_3\/\",\"caption\":\"Iron Grid - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":978,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_3.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sevilla_3-2\/\",\"caption\":\"Iron Grid - Sevilla\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":980,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sevilla\/\",\"caption\":\"Iron Grid - Sevilla\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":982,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_3.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_monte_mayor_3\/\",\"caption\":\"Iron Grid - Monte Mayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":984,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_monte_mayor_2-2\/\",\"caption\":\"Iron Grid - Monte Mayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_7-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_7-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_7-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_7.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":986,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_7.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sotogrande_7\/\",\"caption\":\"Iron Grid - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_6-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_6-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_6-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_6.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":988,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_6.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sotogrande_6\/\",\"caption\":\"Iron Grid - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_5-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_5-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_5-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_5.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":990,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_5.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sotogrande_5\/\",\"caption\":\"Iron Grid - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_4-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_4-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_4-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_4.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":992,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_4.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sotogrande_4\/\",\"caption\":\"Iron Grid - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":994,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_3.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sotogrande_3\/\",\"caption\":\"Iron Grid - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":996,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sotogrande_2-2\/\",\"caption\":\"Iron Grid - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_estepona-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_estepona-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_estepona-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_estepona.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":998,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_estepona.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_estepona-2\/\",\"caption\":\"Iron Grid - Estepona\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1000,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_la_rioja\/\",\"caption\":\"Iron Grid - La Rioja\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_madrid-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_madrid-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_madrid-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_madrid.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1002,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_madrid.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_madrid\/\",\"caption\":\"Iron Grid - Madrid\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1004,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_mijas\/\",\"caption\":\"Iron Grid - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1006,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_monte_mayor\/\",\"caption\":\"Iron Grid - Monte Mayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1008,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_la_rioja_2-2\/\",\"caption\":\"Iron Grid - La Rioja\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1010,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_mijas_2-2\/\",\"caption\":\"Iron Grid - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1012,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sotogrande-2\/\",\"caption\":\"Iron Grid - Sotogrande\"}],\"mediaIDs\":[966,968,970,972,974,976,978,980,982,984,986,988,990,992,994,996,998,1000,1002,1004,1006,1008,1010,1012],\"imageClickEvent\":\"lightbox\",\"captionVisibility\":\"always\",\"imageCaptionAlignment\":\"bottom center\",\"imageCaptionAlignment01\":\"bottom\",\"gridPages\":3,\"feedPagination\":true,\"captionFontSize\":11,\"captionBackgroundEffectAmountHover\":100,\"captionBackgroundColor\":\"rgba(0,0,0,0.3)\",\"paginateDotDistance\":25,\"paginateColor\":\"var(--ast-global-color-0)\",\"paginateColorHover\":\"\",\"imageBoxShadowColor\":\"\",\"tileSize\":0,\"focusList\":[],\"focusListObject\":[],\"feedLayout\":\"grid\",\"imageDisplayCaption\":true,\"galleryImageSize\":\"large\",\"galleryImageSizeTablet\":\"large\",\"galleryImageSizeMobile\":\"medium\",\"disableLazyLoad\":false,\"lightboxDisplayCaptions\":false,\"lightboxThumbnails\":false,\"lightboxDisplayCount\":false,\"lightboxCloseIcon\":\"xmark\",\"lightboxCaptionHeight\":50,\"lightboxCaptionHeightTablet\":\"\",\"lightboxCaptionHeightMobile\":\"\",\"lightboxIconSize\":24,\"lightboxIconSizeTablet\":\"\",\"lightboxIconSizeMobile\":\"\",\"captionDisplayType\":\"overlay\",\"imageCaptionAlignment02\":\"center\",\"imageDefaultCaption\":\"No Caption\",\"captionPaddingTop\":8,\"captionPaddingRight\":8,\"captionPaddingBottom\":8,\"captionPaddingLeft\":8,\"captionPaddingTopTab\":8,\"captionPaddingRightTab\":8,\"captionPaddingBottomTab\":8,\"captionPaddingLeftTab\":8,\"captionPaddingTopMob\":8,\"captionPaddingRightMob\":8,\"captionPaddingBottomMob\":8,\"captionPaddingLeftMob\":8,\"captionPaddingUnit\":\"px\",\"captionPaddingUnitTab\":\"px\",\"captionPaddingUnitMob\":\"px\",\"captionPaddingUnitLink\":true,\"captionGap\":0,\"captionGapUnit\":\"px\",\"columnsDesk\":3,\"columnsTab\":3,\"columnsMob\":2,\"gridImageGap\":8,\"gridImageGapTab\":\"\",\"gridImageGapMob\":\"\",\"gridImageGapUnit\":\"px\",\"gridImageGapUnitTab\":\"px\",\"gridImageGapUnitMob\":\"px\",\"feedMarginTop\":\"\",\"feedMarginRight\":\"\",\"feedMarginBottom\":\"\",\"feedMarginLeft\":\"\",\"feedMarginTopTab\":\"\",\"feedMarginRightTab\":\"\",\"feedMarginBottomTab\":\"\",\"feedMarginLeftTab\":\"\",\"feedMarginTopMob\":\"\",\"feedMarginRightMob\":\"\",\"feedMarginBottomMob\":\"\",\"feedMarginLeftMob\":\"\",\"feedMarginUnit\":\"px\",\"feedMarginUnitTab\":\"px\",\"feedMarginUnitMob\":\"px\",\"feedMarginUnitLink\":true,\"carouselStartAt\":0,\"carouselSquares\":false,\"carouselLoop\":true,\"carouselAutoplay\":true,\"carouselAutoplaySpeed\":2000,\"carouselPauseOnHover\":true,\"carouselTransitionSpeed\":500,\"gridPageNumber\":1,\"paginateUseArrows\":true,\"paginateUseDots\":true,\"paginateUseLoader\":true,\"paginateLimit\":9,\"paginateButtonAlign\":\"center\",\"paginateButtonText\":\"Load More Images\",\"paginateButtonPaddingTop\":\"\",\"paginateButtonPaddingRight\":\"\",\"paginateButtonPaddingBottom\":\"\",\"paginateButtonPaddingLeft\":\"\",\"paginateButtonPaddingTopTab\":\"\",\"paginateButtonPaddingRightTab\":\"\",\"paginateButtonPaddingBottomTab\":\"\",\"paginateButtonPaddingLeftTab\":\"\",\"paginateButtonPaddingTopMob\":\"\",\"paginateButtonPaddingRightMob\":\"\",\"paginateButtonPaddingBottomMob\":\"\",\"paginateButtonPaddingLeftMob\":\"\",\"paginateButtonPaddingUnit\":\"px\",\"paginateButtonPaddingUnitTab\":\"px\",\"paginateButtonPaddingUnitMob\":\"px\",\"paginateButtonPaddingUnitLink\":true,\"imageEnableZoom\":true,\"imageZoomType\":\"zoom-in\",\"captionBackgroundEnableBlur\":false,\"captionBackgroundBlurAmount\":0,\"captionBackgroundBlurAmountHover\":5,\"lightboxEdgeDistance\":10,\"lightboxEdgeDistanceTablet\":\"\",\"lightboxEdgeDistanceMobile\":\"\",\"lightboxBackgroundEnableBlur\":true,\"lightboxBackgroundBlurAmount\":5,\"lightboxBackgroundColor\":\"rgba(0,0,0,0.75)\",\"lightboxIconColor\":\"rgba(255,255,255,1)\",\"lightboxCaptionColor\":\"rgba(255,255,255,1)\",\"lightboxCaptionBackgroundColor\":\"rgba(0,0,0,1)\",\"captionLoadGoogleFonts\":false,\"captionFontFamily\":\"Default\",\"captionFontWeight\":\"\",\"captionFontStyle\":\"normal\",\"captionTransform\":\"\",\"captionDecoration\":\"none\",\"captionFontSizeType\":\"px\",\"captionFontSizeTab\":\"\",\"captionFontSizeMob\":\"\",\"captionLineHeightType\":\"em\",\"captionLineHeight\":\"\",\"captionLineHeightTab\":\"\",\"captionLineHeightMob\":\"\",\"loadMoreLoadGoogleFonts\":false,\"loadMoreFontFamily\":\"Default\",\"loadMoreFontWeight\":\"\",\"loadMoreFontStyle\":\"normal\",\"loadMoreTransform\":\"\",\"loadMoreDecoration\":\"none\",\"loadMoreFontSizeType\":\"px\",\"loadMoreFontSize\":\"\",\"loadMoreFontSizeTab\":\"\",\"loadMoreFontSizeMob\":\"\",\"loadMoreLineHeightType\":\"em\",\"loadMoreLineHeight\":\"\",\"loadMoreLineHeightTab\":\"\",\"loadMoreLineHeightMob\":\"\",\"lightboxLoadGoogleFonts\":false,\"lightboxFontFamily\":\"Default\",\"lightboxFontWeight\":\"\",\"lightboxFontStyle\":\"normal\",\"lightboxTransform\":\"\",\"lightboxDecoration\":\"none\",\"lightboxFontSizeType\":\"px\",\"lightboxFontSize\":\"\",\"lightboxFontSizeTab\":\"\",\"lightboxFontSizeMob\":\"\",\"lightboxLineHeightType\":\"em\",\"lightboxLineHeight\":\"\",\"lightboxLineHeightTab\":\"\",\"lightboxLineHeightMob\":\"\",\"captionBackgroundEffect\":\"none\",\"captionBackgroundEffectHover\":\"none\",\"captionBackgroundEffectAmount\":100,\"captionColor\":\"rgba(255,255,255,1)\",\"captionColorHover\":\"rgba(255,255,255,1)\",\"captionBackgroundColorHover\":\"rgba(0,0,0,0.75)\",\"overlayColor\":\"rgba(0,0,0,0)\",\"overlayColorHover\":\"rgba(0,0,0,0)\",\"captionSeparateColors\":false,\"paginateArrowDistance\":-24,\"paginateArrowDistanceUnit\":\"px\",\"paginateArrowSize\":24,\"paginateDotDistanceUnit\":\"px\",\"paginateLoaderSize\":18,\"paginateButtonTextColor\":\"\",\"paginateButtonTextColorHover\":\"\",\"imageBoxShadowHOffset\":0,\"imageBoxShadowVOffset\":0,\"imageBoxShadowBlur\":\"\",\"imageBoxShadowSpread\":\"\",\"imageBoxShadowPosition\":\"outset\",\"imageBoxShadowColorHover\":\"\",\"imageBoxShadowHOffsetHover\":0,\"imageBoxShadowVOffsetHover\":0,\"imageBoxShadowBlurHover\":\"\",\"imageBoxShadowSpreadHover\":\"\",\"imageBoxShadowPositionHover\":\"outset\",\"arrowBorderTopWidth\":4,\"arrowBorderLeftWidth\":4,\"arrowBorderRightWidth\":4,\"arrowBorderBottomWidth\":4,\"arrowBorderTopLeftRadius\":50,\"arrowBorderTopRightRadius\":50,\"arrowBorderBottomLeftRadius\":50,\"arrowBorderBottomRightRadius\":50,\"arrowBorderRadiusUnit\":\"px\",\"arrowBorderTopWidthTablet\":\"\",\"arrowBorderLeftWidthTablet\":\"\",\"arrowBorderRightWidthTablet\":\"\",\"arrowBorderBottomWidthTablet\":\"\",\"arrowBorderTopLeftRadiusTablet\":\"\",\"arrowBorderTopRightRadiusTablet\":\"\",\"arrowBorderBottomLeftRadiusTablet\":\"\",\"arrowBorderBottomRightRadiusTablet\":\"\",\"arrowBorderRadiusUnitTablet\":\"px\",\"arrowBorderTopWidthMobile\":\"\",\"arrowBorderLeftWidthMobile\":\"\",\"arrowBorderRightWidthMobile\":\"\",\"arrowBorderBottomWidthMobile\":\"\",\"arrowBorderTopLeftRadiusMobile\":\"\",\"arrowBorderTopRightRadiusMobile\":\"\",\"arrowBorderBottomLeftRadiusMobile\":\"\",\"arrowBorderBottomRightRadiusMobile\":\"\",\"arrowBorderRadiusUnitMobile\":\"px\",\"arrowBorderStyle\":\"none\",\"arrowBorderColor\":\"\",\"arrowBorderHColor\":\"\",\"btnBorderTopWidth\":\"\",\"btnBorderLeftWidth\":\"\",\"btnBorderRightWidth\":\"\",\"btnBorderBottomWidth\":\"\",\"btnBorderTopLeftRadius\":\"\",\"btnBorderTopRightRadius\":\"\",\"btnBorderBottomLeftRadius\":\"\",\"btnBorderBottomRightRadius\":\"\",\"btnBorderRadiusUnit\":\"px\",\"btnBorderTopWidthTablet\":\"\",\"btnBorderLeftWidthTablet\":\"\",\"btnBorderRightWidthTablet\":\"\",\"btnBorderBottomWidthTablet\":\"\",\"btnBorderTopLeftRadiusTablet\":\"\",\"btnBorderTopRightRadiusTablet\":\"\",\"btnBorderBottomLeftRadiusTablet\":\"\",\"btnBorderBottomRightRadiusTablet\":\"\",\"btnBorderRadiusUnitTablet\":\"px\",\"btnBorderTopWidthMobile\":\"\",\"btnBorderLeftWidthMobile\":\"\",\"btnBorderRightWidthMobile\":\"\",\"btnBorderBottomWidthMobile\":\"\",\"btnBorderTopLeftRadiusMobile\":\"\",\"btnBorderTopRightRadiusMobile\":\"\",\"btnBorderBottomLeftRadiusMobile\":\"\",\"btnBorderBottomRightRadiusMobile\":\"\",\"btnBorderRadiusUnitMobile\":\"px\",\"btnBorderStyle\":\"\",\"btnBorderColor\":\"\",\"btnBorderHColor\":\"\",\"imageBorderTopWidth\":\"\",\"imageBorderLeftWidth\":\"\",\"imageBorderRightWidth\":\"\",\"imageBorderBottomWidth\":\"\",\"imageBorderTopLeftRadius\":\"\",\"imageBorderTopRightRadius\":\"\",\"imageBorderBottomLeftRadius\":\"\",\"imageBorderBottomRightRadius\":\"\",\"imageBorderRadiusUnit\":\"px\",\"imageBorderTopWidthTablet\":\"\",\"imageBorderLeftWidthTablet\":\"\",\"imageBorderRightWidthTablet\":\"\",\"imageBorderBottomWidthTablet\":\"\",\"imageBorderTopLeftRadiusTablet\":\"\",\"imageBorderTopRightRadiusTablet\":\"\",\"imageBorderBottomLeftRadiusTablet\":\"\",\"imageBorderBottomRightRadiusTablet\":\"\",\"imageBorderRadiusUnitTablet\":\"px\",\"imageBorderTopWidthMobile\":\"\",\"imageBorderLeftWidthMobile\":\"\",\"imageBorderRightWidthMobile\":\"\",\"imageBorderBottomWidthMobile\":\"\",\"imageBorderTopLeftRadiusMobile\":\"\",\"imageBorderTopRightRadiusMobile\":\"\",\"imageBorderBottomLeftRadiusMobile\":\"\",\"imageBorderBottomRightRadiusMobile\":\"\",\"imageBorderRadiusUnitMobile\":\"px\",\"imageBorderStyle\":\"\",\"imageBorderColor\":\"\",\"imageBorderHColor\":\"\",\"mainTitleBorderTopWidth\":2,\"mainTitleBorderLeftWidth\":0,\"mainTitleBorderRightWidth\":0,\"mainTitleBorderBottomWidth\":2,\"mainTitleBorderTopLeftRadius\":\"\",\"mainTitleBorderTopRightRadius\":\"\",\"mainTitleBorderBottomLeftRadius\":\"\",\"mainTitleBorderBottomRightRadius\":\"\",\"mainTitleBorderRadiusUnit\":\"px\",\"mainTitleBorderTopWidthTablet\":\"\",\"mainTitleBorderLeftWidthTablet\":\"\",\"mainTitleBorderRightWidthTablet\":\"\",\"mainTitleBorderBottomWidthTablet\":\"\",\"mainTitleBorderTopLeftRadiusTablet\":\"\",\"mainTitleBorderTopRightRadiusTablet\":\"\",\"mainTitleBorderBottomLeftRadiusTablet\":\"\",\"mainTitleBorderBottomRightRadiusTablet\":\"\",\"mainTitleBorderRadiusUnitTablet\":\"px\",\"mainTitleBorderTopWidthMobile\":\"\",\"mainTitleBorderLeftWidthMobile\":\"\",\"mainTitleBorderRightWidthMobile\":\"\",\"mainTitleBorderBottomWidthMobile\":\"\",\"mainTitleBorderTopLeftRadiusMobile\":\"\",\"mainTitleBorderTopRightRadiusMobile\":\"\",\"mainTitleBorderBottomLeftRadiusMobile\":\"\",\"mainTitleBorderBottomRightRadiusMobile\":\"\",\"mainTitleBorderRadiusUnitMobile\":\"px\",\"mainTitleBorderStyle\":\"\",\"mainTitleBorderColor\":\"\",\"mainTitleBorderHColor\":\"\"}, '.uagb-block-4547cc99', {\"lazy\":true,\"slidesPerView\":1,\"navigation\":{\"nextEl\":\".uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .swiper-button-next\",\"prevEl\":\".uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .swiper-button-prev\"},\"keyboard\":{\"enabled\":true}}, [] );\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', () => {\n\t\t\t\t\tconst blockScope = document.querySelector( '.uagb-block-4547cc99' );\n\t\t\t\t\tif ( ! blockScope ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\t\t\t\t\t\tblockScope.addEventListener('keydown', (event) => {\n\t\t\t\t\t\tif ( 13 === event.keyCode || 32 === event.keyCode ) {\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tblockScope.click();\n\t\t\t\t\t\t}\n\t\t\t\t\t} );\n\n\t\t\t\t\tlet lightboxSwiper = null;\n\t\t\t\t\tlet thumbnailSwiper = null;\n\n\t\t\t\t\t\t\t\t\t\tlet lightboxSettings = {\"lazy\":true,\"slidesPerView\":1,\"navigation\":{\"nextEl\":\".uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .swiper-button-next\",\"prevEl\":\".uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .swiper-button-prev\"},\"keyboard\":{\"enabled\":true}};\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tlightboxSwiper = new Swiper( \".uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main\",\n\t\t\t\t\t\t{\"lazy\":true,\"slidesPerView\":1,\"navigation\":{\"nextEl\":\".uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .swiper-button-next\",\"prevEl\":\".uagb-block-4547cc99+.spectra-image-gallery__control-lightbox .swiper-button-prev\"},\"keyboard\":{\"enabled\":true}}\t\t\t\t\t);\n\t\t\t\t\tloadLightBoxImages( blockScope, lightboxSwiper, null, {\"block_id\":\"4547cc99\",\"classMigrate\":true,\"readyToRender\":true,\"mediaGallery\":[{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":966,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sevilla_2\/\",\"caption\":\"Iron Grid - Sevilla\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_7-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_7-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_7-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_7.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":968,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_7.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_mijas_7\/\",\"caption\":\"Iron Grid - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_6-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_6-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_6-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_6.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":970,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_6.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_mijas_6\/\",\"caption\":\"Iron Grid - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_5-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_5-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_5-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_5.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":972,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_5.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_mijas_5\/\",\"caption\":\"Iron Grid - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_4-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_4-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_4-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_4.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":974,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_4.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_mijas_4\/\",\"caption\":\"Iron Grid - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":976,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_3.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_mijas_3\/\",\"caption\":\"Iron Grid - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":978,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla_3.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sevilla_3-2\/\",\"caption\":\"Iron Grid - Sevilla\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":980,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sevilla.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sevilla\/\",\"caption\":\"Iron Grid - Sevilla\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":982,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_3.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_monte_mayor_3\/\",\"caption\":\"Iron Grid - Monte Mayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":984,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_monte_mayor_2-2\/\",\"caption\":\"Iron Grid - Monte Mayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_7-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_7-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_7-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_7.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":986,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_7.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sotogrande_7\/\",\"caption\":\"Iron Grid - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_6-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_6-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_6-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_6.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":988,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_6.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sotogrande_6\/\",\"caption\":\"Iron Grid - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_5-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_5-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_5-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_5.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":990,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_5.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sotogrande_5\/\",\"caption\":\"Iron Grid - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_4-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_4-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_4-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_4.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":992,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_4.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sotogrande_4\/\",\"caption\":\"Iron Grid - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":994,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_3.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sotogrande_3\/\",\"caption\":\"Iron Grid - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":996,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sotogrande_2-2\/\",\"caption\":\"Iron Grid - Sotogrande\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_estepona-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_estepona-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_estepona-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_estepona.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":998,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_estepona.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_estepona-2\/\",\"caption\":\"Iron Grid - Estepona\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1000,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_la_rioja\/\",\"caption\":\"Iron Grid - La Rioja\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_madrid-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_madrid-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_madrid-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_madrid.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1002,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_madrid.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_madrid\/\",\"caption\":\"Iron Grid - Madrid\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1004,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_mijas\/\",\"caption\":\"Iron Grid - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1006,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_monte_mayor.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_monte_mayor\/\",\"caption\":\"Iron Grid - Monte Mayor\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1008,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_la_rioja_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_la_rioja_2-2\/\",\"caption\":\"Iron Grid - La Rioja\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1010,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_mijas_2.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_mijas_2-2\/\",\"caption\":\"Iron Grid - Mijas\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1012,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/gaviones_iron_grid_sotogrande.jpg\",\"alt\":\"\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/gaviones_iron_grid_sotogrande-2\/\",\"caption\":\"Iron Grid - Sotogrande\"}],\"mediaIDs\":[966,968,970,972,974,976,978,980,982,984,986,988,990,992,994,996,998,1000,1002,1004,1006,1008,1010,1012],\"imageClickEvent\":\"lightbox\",\"captionVisibility\":\"always\",\"imageCaptionAlignment\":\"bottom center\",\"imageCaptionAlignment01\":\"bottom\",\"gridPages\":3,\"feedPagination\":true,\"captionFontSize\":11,\"captionBackgroundEffectAmountHover\":100,\"captionBackgroundColor\":\"rgba(0,0,0,0.3)\",\"paginateDotDistance\":25,\"paginateColor\":\"var(--ast-global-color-0)\",\"paginateColorHover\":\"\",\"imageBoxShadowColor\":\"\",\"tileSize\":0,\"focusList\":[],\"focusListObject\":[],\"feedLayout\":\"grid\",\"imageDisplayCaption\":true,\"galleryImageSize\":\"large\",\"galleryImageSizeTablet\":\"large\",\"galleryImageSizeMobile\":\"medium\",\"disableLazyLoad\":false,\"lightboxDisplayCaptions\":false,\"lightboxThumbnails\":false,\"lightboxDisplayCount\":false,\"lightboxCloseIcon\":\"xmark\",\"lightboxCaptionHeight\":50,\"lightboxCaptionHeightTablet\":\"\",\"lightboxCaptionHeightMobile\":\"\",\"lightboxIconSize\":24,\"lightboxIconSizeTablet\":\"\",\"lightboxIconSizeMobile\":\"\",\"captionDisplayType\":\"overlay\",\"imageCaptionAlignment02\":\"center\",\"imageDefaultCaption\":\"No Caption\",\"captionPaddingTop\":8,\"captionPaddingRight\":8,\"captionPaddingBottom\":8,\"captionPaddingLeft\":8,\"captionPaddingTopTab\":8,\"captionPaddingRightTab\":8,\"captionPaddingBottomTab\":8,\"captionPaddingLeftTab\":8,\"captionPaddingTopMob\":8,\"captionPaddingRightMob\":8,\"captionPaddingBottomMob\":8,\"captionPaddingLeftMob\":8,\"captionPaddingUnit\":\"px\",\"captionPaddingUnitTab\":\"px\",\"captionPaddingUnitMob\":\"px\",\"captionPaddingUnitLink\":true,\"captionGap\":0,\"captionGapUnit\":\"px\",\"columnsDesk\":3,\"columnsTab\":3,\"columnsMob\":2,\"gridImageGap\":8,\"gridImageGapTab\":\"\",\"gridImageGapMob\":\"\",\"gridImageGapUnit\":\"px\",\"gridImageGapUnitTab\":\"px\",\"gridImageGapUnitMob\":\"px\",\"feedMarginTop\":\"\",\"feedMarginRight\":\"\",\"feedMarginBottom\":\"\",\"feedMarginLeft\":\"\",\"feedMarginTopTab\":\"\",\"feedMarginRightTab\":\"\",\"feedMarginBottomTab\":\"\",\"feedMarginLeftTab\":\"\",\"feedMarginTopMob\":\"\",\"feedMarginRightMob\":\"\",\"feedMarginBottomMob\":\"\",\"feedMarginLeftMob\":\"\",\"feedMarginUnit\":\"px\",\"feedMarginUnitTab\":\"px\",\"feedMarginUnitMob\":\"px\",\"feedMarginUnitLink\":true,\"carouselStartAt\":0,\"carouselSquares\":false,\"carouselLoop\":true,\"carouselAutoplay\":true,\"carouselAutoplaySpeed\":2000,\"carouselPauseOnHover\":true,\"carouselTransitionSpeed\":500,\"gridPageNumber\":1,\"paginateUseArrows\":true,\"paginateUseDots\":true,\"paginateUseLoader\":true,\"paginateLimit\":9,\"paginateButtonAlign\":\"center\",\"paginateButtonText\":\"Load More Images\",\"paginateButtonPaddingTop\":\"\",\"paginateButtonPaddingRight\":\"\",\"paginateButtonPaddingBottom\":\"\",\"paginateButtonPaddingLeft\":\"\",\"paginateButtonPaddingTopTab\":\"\",\"paginateButtonPaddingRightTab\":\"\",\"paginateButtonPaddingBottomTab\":\"\",\"paginateButtonPaddingLeftTab\":\"\",\"paginateButtonPaddingTopMob\":\"\",\"paginateButtonPaddingRightMob\":\"\",\"paginateButtonPaddingBottomMob\":\"\",\"paginateButtonPaddingLeftMob\":\"\",\"paginateButtonPaddingUnit\":\"px\",\"paginateButtonPaddingUnitTab\":\"px\",\"paginateButtonPaddingUnitMob\":\"px\",\"paginateButtonPaddingUnitLink\":true,\"imageEnableZoom\":true,\"imageZoomType\":\"zoom-in\",\"captionBackgroundEnableBlur\":false,\"captionBackgroundBlurAmount\":0,\"captionBackgroundBlurAmountHover\":5,\"lightboxEdgeDistance\":10,\"lightboxEdgeDistanceTablet\":\"\",\"lightboxEdgeDistanceMobile\":\"\",\"lightboxBackgroundEnableBlur\":true,\"lightboxBackgroundBlurAmount\":5,\"lightboxBackgroundColor\":\"rgba(0,0,0,0.75)\",\"lightboxIconColor\":\"rgba(255,255,255,1)\",\"lightboxCaptionColor\":\"rgba(255,255,255,1)\",\"lightboxCaptionBackgroundColor\":\"rgba(0,0,0,1)\",\"captionLoadGoogleFonts\":false,\"captionFontFamily\":\"Default\",\"captionFontWeight\":\"\",\"captionFontStyle\":\"normal\",\"captionTransform\":\"\",\"captionDecoration\":\"none\",\"captionFontSizeType\":\"px\",\"captionFontSizeTab\":\"\",\"captionFontSizeMob\":\"\",\"captionLineHeightType\":\"em\",\"captionLineHeight\":\"\",\"captionLineHeightTab\":\"\",\"captionLineHeightMob\":\"\",\"loadMoreLoadGoogleFonts\":false,\"loadMoreFontFamily\":\"Default\",\"loadMoreFontWeight\":\"\",\"loadMoreFontStyle\":\"normal\",\"loadMoreTransform\":\"\",\"loadMoreDecoration\":\"none\",\"loadMoreFontSizeType\":\"px\",\"loadMoreFontSize\":\"\",\"loadMoreFontSizeTab\":\"\",\"loadMoreFontSizeMob\":\"\",\"loadMoreLineHeightType\":\"em\",\"loadMoreLineHeight\":\"\",\"loadMoreLineHeightTab\":\"\",\"loadMoreLineHeightMob\":\"\",\"lightboxLoadGoogleFonts\":false,\"lightboxFontFamily\":\"Default\",\"lightboxFontWeight\":\"\",\"lightboxFontStyle\":\"normal\",\"lightboxTransform\":\"\",\"lightboxDecoration\":\"none\",\"lightboxFontSizeType\":\"px\",\"lightboxFontSize\":\"\",\"lightboxFontSizeTab\":\"\",\"lightboxFontSizeMob\":\"\",\"lightboxLineHeightType\":\"em\",\"lightboxLineHeight\":\"\",\"lightboxLineHeightTab\":\"\",\"lightboxLineHeightMob\":\"\",\"captionBackgroundEffect\":\"none\",\"captionBackgroundEffectHover\":\"none\",\"captionBackgroundEffectAmount\":100,\"captionColor\":\"rgba(255,255,255,1)\",\"captionColorHover\":\"rgba(255,255,255,1)\",\"captionBackgroundColorHover\":\"rgba(0,0,0,0.75)\",\"overlayColor\":\"rgba(0,0,0,0)\",\"overlayColorHover\":\"rgba(0,0,0,0)\",\"captionSeparateColors\":false,\"paginateArrowDistance\":-24,\"paginateArrowDistanceUnit\":\"px\",\"paginateArrowSize\":24,\"paginateDotDistanceUnit\":\"px\",\"paginateLoaderSize\":18,\"paginateButtonTextColor\":\"\",\"paginateButtonTextColorHover\":\"\",\"imageBoxShadowHOffset\":0,\"imageBoxShadowVOffset\":0,\"imageBoxShadowBlur\":\"\",\"imageBoxShadowSpread\":\"\",\"imageBoxShadowPosition\":\"outset\",\"imageBoxShadowColorHover\":\"\",\"imageBoxShadowHOffsetHover\":0,\"imageBoxShadowVOffsetHover\":0,\"imageBoxShadowBlurHover\":\"\",\"imageBoxShadowSpreadHover\":\"\",\"imageBoxShadowPositionHover\":\"outset\",\"arrowBorderTopWidth\":4,\"arrowBorderLeftWidth\":4,\"arrowBorderRightWidth\":4,\"arrowBorderBottomWidth\":4,\"arrowBorderTopLeftRadius\":50,\"arrowBorderTopRightRadius\":50,\"arrowBorderBottomLeftRadius\":50,\"arrowBorderBottomRightRadius\":50,\"arrowBorderRadiusUnit\":\"px\",\"arrowBorderTopWidthTablet\":\"\",\"arrowBorderLeftWidthTablet\":\"\",\"arrowBorderRightWidthTablet\":\"\",\"arrowBorderBottomWidthTablet\":\"\",\"arrowBorderTopLeftRadiusTablet\":\"\",\"arrowBorderTopRightRadiusTablet\":\"\",\"arrowBorderBottomLeftRadiusTablet\":\"\",\"arrowBorderBottomRightRadiusTablet\":\"\",\"arrowBorderRadiusUnitTablet\":\"px\",\"arrowBorderTopWidthMobile\":\"\",\"arrowBorderLeftWidthMobile\":\"\",\"arrowBorderRightWidthMobile\":\"\",\"arrowBorderBottomWidthMobile\":\"\",\"arrowBorderTopLeftRadiusMobile\":\"\",\"arrowBorderTopRightRadiusMobile\":\"\",\"arrowBorderBottomLeftRadiusMobile\":\"\",\"arrowBorderBottomRightRadiusMobile\":\"\",\"arrowBorderRadiusUnitMobile\":\"px\",\"arrowBorderStyle\":\"none\",\"arrowBorderColor\":\"\",\"arrowBorderHColor\":\"\",\"btnBorderTopWidth\":\"\",\"btnBorderLeftWidth\":\"\",\"btnBorderRightWidth\":\"\",\"btnBorderBottomWidth\":\"\",\"btnBorderTopLeftRadius\":\"\",\"btnBorderTopRightRadius\":\"\",\"btnBorderBottomLeftRadius\":\"\",\"btnBorderBottomRightRadius\":\"\",\"btnBorderRadiusUnit\":\"px\",\"btnBorderTopWidthTablet\":\"\",\"btnBorderLeftWidthTablet\":\"\",\"btnBorderRightWidthTablet\":\"\",\"btnBorderBottomWidthTablet\":\"\",\"btnBorderTopLeftRadiusTablet\":\"\",\"btnBorderTopRightRadiusTablet\":\"\",\"btnBorderBottomLeftRadiusTablet\":\"\",\"btnBorderBottomRightRadiusTablet\":\"\",\"btnBorderRadiusUnitTablet\":\"px\",\"btnBorderTopWidthMobile\":\"\",\"btnBorderLeftWidthMobile\":\"\",\"btnBorderRightWidthMobile\":\"\",\"btnBorderBottomWidthMobile\":\"\",\"btnBorderTopLeftRadiusMobile\":\"\",\"btnBorderTopRightRadiusMobile\":\"\",\"btnBorderBottomLeftRadiusMobile\":\"\",\"btnBorderBottomRightRadiusMobile\":\"\",\"btnBorderRadiusUnitMobile\":\"px\",\"btnBorderStyle\":\"\",\"btnBorderColor\":\"\",\"btnBorderHColor\":\"\",\"imageBorderTopWidth\":\"\",\"imageBorderLeftWidth\":\"\",\"imageBorderRightWidth\":\"\",\"imageBorderBottomWidth\":\"\",\"imageBorderTopLeftRadius\":\"\",\"imageBorderTopRightRadius\":\"\",\"imageBorderBottomLeftRadius\":\"\",\"imageBorderBottomRightRadius\":\"\",\"imageBorderRadiusUnit\":\"px\",\"imageBorderTopWidthTablet\":\"\",\"imageBorderLeftWidthTablet\":\"\",\"imageBorderRightWidthTablet\":\"\",\"imageBorderBottomWidthTablet\":\"\",\"imageBorderTopLeftRadiusTablet\":\"\",\"imageBorderTopRightRadiusTablet\":\"\",\"imageBorderBottomLeftRadiusTablet\":\"\",\"imageBorderBottomRightRadiusTablet\":\"\",\"imageBorderRadiusUnitTablet\":\"px\",\"imageBorderTopWidthMobile\":\"\",\"imageBorderLeftWidthMobile\":\"\",\"imageBorderRightWidthMobile\":\"\",\"imageBorderBottomWidthMobile\":\"\",\"imageBorderTopLeftRadiusMobile\":\"\",\"imageBorderTopRightRadiusMobile\":\"\",\"imageBorderBottomLeftRadiusMobile\":\"\",\"imageBorderBottomRightRadiusMobile\":\"\",\"imageBorderRadiusUnitMobile\":\"px\",\"imageBorderStyle\":\"\",\"imageBorderColor\":\"\",\"imageBorderHColor\":\"\",\"mainTitleBorderTopWidth\":2,\"mainTitleBorderLeftWidth\":0,\"mainTitleBorderRightWidth\":0,\"mainTitleBorderBottomWidth\":2,\"mainTitleBorderTopLeftRadius\":\"\",\"mainTitleBorderTopRightRadius\":\"\",\"mainTitleBorderBottomLeftRadius\":\"\",\"mainTitleBorderBottomRightRadius\":\"\",\"mainTitleBorderRadiusUnit\":\"px\",\"mainTitleBorderTopWidthTablet\":\"\",\"mainTitleBorderLeftWidthTablet\":\"\",\"mainTitleBorderRightWidthTablet\":\"\",\"mainTitleBorderBottomWidthTablet\":\"\",\"mainTitleBorderTopLeftRadiusTablet\":\"\",\"mainTitleBorderTopRightRadiusTablet\":\"\",\"mainTitleBorderBottomLeftRadiusTablet\":\"\",\"mainTitleBorderBottomRightRadiusTablet\":\"\",\"mainTitleBorderRadiusUnitTablet\":\"px\",\"mainTitleBorderTopWidthMobile\":\"\",\"mainTitleBorderLeftWidthMobile\":\"\",\"mainTitleBorderRightWidthMobile\":\"\",\"mainTitleBorderBottomWidthMobile\":\"\",\"mainTitleBorderTopLeftRadiusMobile\":\"\",\"mainTitleBorderTopRightRadiusMobile\":\"\",\"mainTitleBorderBottomLeftRadiusMobile\":\"\",\"mainTitleBorderBottomRightRadiusMobile\":\"\",\"mainTitleBorderRadiusUnitMobile\":\"px\",\"mainTitleBorderStyle\":\"\",\"mainTitleBorderColor\":\"\",\"mainTitleBorderHColor\":\"\"}, thumbnailSwiper );\n\t\t\t\t\t\t\t\tconst regexCustomURL = new RegExp( '^((http|https):\/\/)(www.)?[a-zA-Z0-9@:%._\\+~#?&\/\/=\\-]{2,256}\\.[a-z]{2,6}\\b([-a-zA-Z0-9@:%._\\+~#?&\/\/=]*)$' );\n\t\t\tconst customLinks = {};\n\t\t\tconst customLinksBehaviour = {};\n\n\t\t\tconst getCustomURL = ( caption ) => {\n\t\t\t\tif ( ! customLinks ) {\n\t\t\t\t\treturn undefined;\n\t\t\t\t}\n\t\t\t\tconst imageID = parseInt( caption.getAttribute( 'data-spectra-gallery-image-id' ) );\n\t\t\t\treturn ( regexCustomURL.test( customLinks[ imageID ] ) ? customLinks[ imageID ] : undefined );\n\t\t\t}\n\n\t\t\tconst getCustomLinkBehaviour = (caption) => {\n\t\t\t\tif (!customLinksBehaviour) {\n\t\t\t\t\treturn true;\n\t\t\t\t}\n\t\t\t\tconst imageId = parseInt(caption.getAttribute('data-spectra-gallery-image-id'));\n\t\t\t\treturn !(customLinksBehaviour[imageId] === true);\n\t\t\t};\n\n\t\t\tconst captions = lightboxSwiper.el.querySelectorAll( '.spectra-image-gallery__control-lightbox--caption' );\n\t\t\tfor ( let i = 0; i < captions.length; i++ ) {\n\t\t\t\tconst customURL = getCustomURL( captions[ i ] );\n\t\t\t\tif ( customURL ) {\n\t\t\t\t\tconst anchor = document.createElement( 'a' );\n\t\t\t\t\tanchor.target = getCustomLinkBehaviour( captions[ i ] ) ? '_blank' : '_self';\n\t\t\t\t\tanchor.rel = 'noopener noreferrer';\n\t\t\t\t\tanchor.href = customURL;\n\t\t\t\t\tanchor.innerHTML = captions[ i ].innerHTML;\n\t\t\t\t\tcaptions[ i ].textContent = '';\n\t\t\t\t\tcaptions[ i ].appendChild( anchor );\n\t\t\t\t}\n\t\t\t}\n\t\t\t\t\t\t} );\n\t\t\tjQuery(document).ready(function(){if(window.matchMedia&&window.matchMedia(\"(hover:none)\").matches){jQuery(\".wp-block-uagb-image-gallery.uagb-block-4547cc99\").addClass(\"spectra-touch-device\");}});\t\t\t\twindow.addEventListener( 'DOMContentLoaded', function() {\n\t\t\t\t\tconst scope = document.querySelector( '.uagb-block-5cc8c098' );\n\t\t\t\t\tif ( scope ){\n\t\t\t\t\t\tif ( scope.children[0].classList.contains( 'spectra-image-gallery__layout--isogrid' ) ) {\n\t\t\t\t\t\t\tsetTimeout( function() {\n\t\t\t\t\t\t\t\tconst element = scope.querySelector( '.spectra-image-gallery__layout--isogrid' );\n\t\t\t\t\t\t\t\tconst isotope = new Isotope( element, {\n\t\t\t\t\t\t\t\t\titemSelector: '.spectra-image-gallery__media-wrapper--isotope',\n\t\t\t\t\t\t\t\t\tlayoutMode: 'fitRows',\n\t\t\t\t\t\t\t\t} );\n\t\t\t\t\t\t\t\timagesLoaded( element ).on( 'progress', function() {\n\t\t\t\t\t\t\t\t\tisotope.layout();\n\t\t\t\t\t\t\t\t});\n\t\t\t\t\t\t\t\tUAGBImageGalleryMasonry.initByOffset( element, isotope );\n\t\t\t\t\t\t\t}, 500 );\n\t\t\t\t\t\t}\n\t\t\t\t\t\tUAGBImageGalleryPagedGrid.init( {\"block_id\":\"5cc8c098\",\"classMigrate\":true,\"readyToRender\":true,\"mediaGallery\":[{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1014,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_2.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_7-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_7-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_7-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_7.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1016,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_7.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_7\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_8-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_8-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_8-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_8.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1018,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_8.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_8-2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_13-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_13-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_13-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_13.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1020,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_13.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_13\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_14-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_14-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_14-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_14.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1022,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_14.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_14\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_15-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_15-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_15-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_15.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_15.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_15-2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1026,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block-2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1028,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_3.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_3\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_4-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_4-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_4-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_4.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1030,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_4.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_4\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_5-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_5-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_5-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_5.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1032,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_5.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_5\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_9-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_9-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_9-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_9.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1034,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_9.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_9-2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_10-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_10-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_10-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_10.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1036,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_10.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_10\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_11-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_11-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_11-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_11.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1038,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_11.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_11-2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_12-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_12-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_12-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_12.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1040,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_12.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_12-2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1042,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_1.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_1-2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_6-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_6-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_6-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_6.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1044,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_6.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_6\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_16-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_16-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_16-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_16.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1046,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_16.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_16-2\/\",\"caption\":\"Eco Block Wall\"}],\"mediaIDs\":[1014,1016,1018,1020,1022,1024,1026,1028,1030,1032,1034,1036,1038,1040,1042,1044,1046],\"imageClickEvent\":\"lightbox\",\"captionVisibility\":\"always\",\"imageCaptionAlignment\":\"bottom center\",\"imageCaptionAlignment01\":\"bottom\",\"gridPages\":2,\"feedPagination\":true,\"captionFontSize\":11,\"captionBackgroundEffectAmountHover\":100,\"captionBackgroundColor\":\"rgba(0,0,0,0.3)\",\"paginateDotDistance\":25,\"paginateColor\":\"var(--ast-global-color-0)\",\"paginateColorHover\":\"\",\"imageBoxShadowColor\":\"\",\"tileSize\":0,\"focusList\":[],\"focusListObject\":[],\"feedLayout\":\"grid\",\"imageDisplayCaption\":true,\"galleryImageSize\":\"large\",\"galleryImageSizeTablet\":\"large\",\"galleryImageSizeMobile\":\"medium\",\"disableLazyLoad\":false,\"lightboxDisplayCaptions\":false,\"lightboxThumbnails\":false,\"lightboxDisplayCount\":false,\"lightboxCloseIcon\":\"xmark\",\"lightboxCaptionHeight\":50,\"lightboxCaptionHeightTablet\":\"\",\"lightboxCaptionHeightMobile\":\"\",\"lightboxIconSize\":24,\"lightboxIconSizeTablet\":\"\",\"lightboxIconSizeMobile\":\"\",\"captionDisplayType\":\"overlay\",\"imageCaptionAlignment02\":\"center\",\"imageDefaultCaption\":\"No Caption\",\"captionPaddingTop\":8,\"captionPaddingRight\":8,\"captionPaddingBottom\":8,\"captionPaddingLeft\":8,\"captionPaddingTopTab\":8,\"captionPaddingRightTab\":8,\"captionPaddingBottomTab\":8,\"captionPaddingLeftTab\":8,\"captionPaddingTopMob\":8,\"captionPaddingRightMob\":8,\"captionPaddingBottomMob\":8,\"captionPaddingLeftMob\":8,\"captionPaddingUnit\":\"px\",\"captionPaddingUnitTab\":\"px\",\"captionPaddingUnitMob\":\"px\",\"captionPaddingUnitLink\":true,\"captionGap\":0,\"captionGapUnit\":\"px\",\"columnsDesk\":3,\"columnsTab\":3,\"columnsMob\":2,\"gridImageGap\":8,\"gridImageGapTab\":\"\",\"gridImageGapMob\":\"\",\"gridImageGapUnit\":\"px\",\"gridImageGapUnitTab\":\"px\",\"gridImageGapUnitMob\":\"px\",\"feedMarginTop\":\"\",\"feedMarginRight\":\"\",\"feedMarginBottom\":\"\",\"feedMarginLeft\":\"\",\"feedMarginTopTab\":\"\",\"feedMarginRightTab\":\"\",\"feedMarginBottomTab\":\"\",\"feedMarginLeftTab\":\"\",\"feedMarginTopMob\":\"\",\"feedMarginRightMob\":\"\",\"feedMarginBottomMob\":\"\",\"feedMarginLeftMob\":\"\",\"feedMarginUnit\":\"px\",\"feedMarginUnitTab\":\"px\",\"feedMarginUnitMob\":\"px\",\"feedMarginUnitLink\":true,\"carouselStartAt\":0,\"carouselSquares\":false,\"carouselLoop\":true,\"carouselAutoplay\":true,\"carouselAutoplaySpeed\":2000,\"carouselPauseOnHover\":true,\"carouselTransitionSpeed\":500,\"gridPageNumber\":1,\"paginateUseArrows\":true,\"paginateUseDots\":true,\"paginateUseLoader\":true,\"paginateLimit\":9,\"paginateButtonAlign\":\"center\",\"paginateButtonText\":\"Load More Images\",\"paginateButtonPaddingTop\":\"\",\"paginateButtonPaddingRight\":\"\",\"paginateButtonPaddingBottom\":\"\",\"paginateButtonPaddingLeft\":\"\",\"paginateButtonPaddingTopTab\":\"\",\"paginateButtonPaddingRightTab\":\"\",\"paginateButtonPaddingBottomTab\":\"\",\"paginateButtonPaddingLeftTab\":\"\",\"paginateButtonPaddingTopMob\":\"\",\"paginateButtonPaddingRightMob\":\"\",\"paginateButtonPaddingBottomMob\":\"\",\"paginateButtonPaddingLeftMob\":\"\",\"paginateButtonPaddingUnit\":\"px\",\"paginateButtonPaddingUnitTab\":\"px\",\"paginateButtonPaddingUnitMob\":\"px\",\"paginateButtonPaddingUnitLink\":true,\"imageEnableZoom\":true,\"imageZoomType\":\"zoom-in\",\"captionBackgroundEnableBlur\":false,\"captionBackgroundBlurAmount\":0,\"captionBackgroundBlurAmountHover\":5,\"lightboxEdgeDistance\":10,\"lightboxEdgeDistanceTablet\":\"\",\"lightboxEdgeDistanceMobile\":\"\",\"lightboxBackgroundEnableBlur\":true,\"lightboxBackgroundBlurAmount\":5,\"lightboxBackgroundColor\":\"rgba(0,0,0,0.75)\",\"lightboxIconColor\":\"rgba(255,255,255,1)\",\"lightboxCaptionColor\":\"rgba(255,255,255,1)\",\"lightboxCaptionBackgroundColor\":\"rgba(0,0,0,1)\",\"captionLoadGoogleFonts\":false,\"captionFontFamily\":\"Default\",\"captionFontWeight\":\"\",\"captionFontStyle\":\"normal\",\"captionTransform\":\"\",\"captionDecoration\":\"none\",\"captionFontSizeType\":\"px\",\"captionFontSizeTab\":\"\",\"captionFontSizeMob\":\"\",\"captionLineHeightType\":\"em\",\"captionLineHeight\":\"\",\"captionLineHeightTab\":\"\",\"captionLineHeightMob\":\"\",\"loadMoreLoadGoogleFonts\":false,\"loadMoreFontFamily\":\"Default\",\"loadMoreFontWeight\":\"\",\"loadMoreFontStyle\":\"normal\",\"loadMoreTransform\":\"\",\"loadMoreDecoration\":\"none\",\"loadMoreFontSizeType\":\"px\",\"loadMoreFontSize\":\"\",\"loadMoreFontSizeTab\":\"\",\"loadMoreFontSizeMob\":\"\",\"loadMoreLineHeightType\":\"em\",\"loadMoreLineHeight\":\"\",\"loadMoreLineHeightTab\":\"\",\"loadMoreLineHeightMob\":\"\",\"lightboxLoadGoogleFonts\":false,\"lightboxFontFamily\":\"Default\",\"lightboxFontWeight\":\"\",\"lightboxFontStyle\":\"normal\",\"lightboxTransform\":\"\",\"lightboxDecoration\":\"none\",\"lightboxFontSizeType\":\"px\",\"lightboxFontSize\":\"\",\"lightboxFontSizeTab\":\"\",\"lightboxFontSizeMob\":\"\",\"lightboxLineHeightType\":\"em\",\"lightboxLineHeight\":\"\",\"lightboxLineHeightTab\":\"\",\"lightboxLineHeightMob\":\"\",\"captionBackgroundEffect\":\"none\",\"captionBackgroundEffectHover\":\"none\",\"captionBackgroundEffectAmount\":100,\"captionColor\":\"rgba(255,255,255,1)\",\"captionColorHover\":\"rgba(255,255,255,1)\",\"captionBackgroundColorHover\":\"rgba(0,0,0,0.75)\",\"overlayColor\":\"rgba(0,0,0,0)\",\"overlayColorHover\":\"rgba(0,0,0,0)\",\"captionSeparateColors\":false,\"paginateArrowDistance\":-24,\"paginateArrowDistanceUnit\":\"px\",\"paginateArrowSize\":24,\"paginateDotDistanceUnit\":\"px\",\"paginateLoaderSize\":18,\"paginateButtonTextColor\":\"\",\"paginateButtonTextColorHover\":\"\",\"imageBoxShadowHOffset\":0,\"imageBoxShadowVOffset\":0,\"imageBoxShadowBlur\":\"\",\"imageBoxShadowSpread\":\"\",\"imageBoxShadowPosition\":\"outset\",\"imageBoxShadowColorHover\":\"\",\"imageBoxShadowHOffsetHover\":0,\"imageBoxShadowVOffsetHover\":0,\"imageBoxShadowBlurHover\":\"\",\"imageBoxShadowSpreadHover\":\"\",\"imageBoxShadowPositionHover\":\"outset\",\"arrowBorderTopWidth\":4,\"arrowBorderLeftWidth\":4,\"arrowBorderRightWidth\":4,\"arrowBorderBottomWidth\":4,\"arrowBorderTopLeftRadius\":50,\"arrowBorderTopRightRadius\":50,\"arrowBorderBottomLeftRadius\":50,\"arrowBorderBottomRightRadius\":50,\"arrowBorderRadiusUnit\":\"px\",\"arrowBorderTopWidthTablet\":\"\",\"arrowBorderLeftWidthTablet\":\"\",\"arrowBorderRightWidthTablet\":\"\",\"arrowBorderBottomWidthTablet\":\"\",\"arrowBorderTopLeftRadiusTablet\":\"\",\"arrowBorderTopRightRadiusTablet\":\"\",\"arrowBorderBottomLeftRadiusTablet\":\"\",\"arrowBorderBottomRightRadiusTablet\":\"\",\"arrowBorderRadiusUnitTablet\":\"px\",\"arrowBorderTopWidthMobile\":\"\",\"arrowBorderLeftWidthMobile\":\"\",\"arrowBorderRightWidthMobile\":\"\",\"arrowBorderBottomWidthMobile\":\"\",\"arrowBorderTopLeftRadiusMobile\":\"\",\"arrowBorderTopRightRadiusMobile\":\"\",\"arrowBorderBottomLeftRadiusMobile\":\"\",\"arrowBorderBottomRightRadiusMobile\":\"\",\"arrowBorderRadiusUnitMobile\":\"px\",\"arrowBorderStyle\":\"none\",\"arrowBorderColor\":\"\",\"arrowBorderHColor\":\"\",\"btnBorderTopWidth\":\"\",\"btnBorderLeftWidth\":\"\",\"btnBorderRightWidth\":\"\",\"btnBorderBottomWidth\":\"\",\"btnBorderTopLeftRadius\":\"\",\"btnBorderTopRightRadius\":\"\",\"btnBorderBottomLeftRadius\":\"\",\"btnBorderBottomRightRadius\":\"\",\"btnBorderRadiusUnit\":\"px\",\"btnBorderTopWidthTablet\":\"\",\"btnBorderLeftWidthTablet\":\"\",\"btnBorderRightWidthTablet\":\"\",\"btnBorderBottomWidthTablet\":\"\",\"btnBorderTopLeftRadiusTablet\":\"\",\"btnBorderTopRightRadiusTablet\":\"\",\"btnBorderBottomLeftRadiusTablet\":\"\",\"btnBorderBottomRightRadiusTablet\":\"\",\"btnBorderRadiusUnitTablet\":\"px\",\"btnBorderTopWidthMobile\":\"\",\"btnBorderLeftWidthMobile\":\"\",\"btnBorderRightWidthMobile\":\"\",\"btnBorderBottomWidthMobile\":\"\",\"btnBorderTopLeftRadiusMobile\":\"\",\"btnBorderTopRightRadiusMobile\":\"\",\"btnBorderBottomLeftRadiusMobile\":\"\",\"btnBorderBottomRightRadiusMobile\":\"\",\"btnBorderRadiusUnitMobile\":\"px\",\"btnBorderStyle\":\"\",\"btnBorderColor\":\"\",\"btnBorderHColor\":\"\",\"imageBorderTopWidth\":\"\",\"imageBorderLeftWidth\":\"\",\"imageBorderRightWidth\":\"\",\"imageBorderBottomWidth\":\"\",\"imageBorderTopLeftRadius\":\"\",\"imageBorderTopRightRadius\":\"\",\"imageBorderBottomLeftRadius\":\"\",\"imageBorderBottomRightRadius\":\"\",\"imageBorderRadiusUnit\":\"px\",\"imageBorderTopWidthTablet\":\"\",\"imageBorderLeftWidthTablet\":\"\",\"imageBorderRightWidthTablet\":\"\",\"imageBorderBottomWidthTablet\":\"\",\"imageBorderTopLeftRadiusTablet\":\"\",\"imageBorderTopRightRadiusTablet\":\"\",\"imageBorderBottomLeftRadiusTablet\":\"\",\"imageBorderBottomRightRadiusTablet\":\"\",\"imageBorderRadiusUnitTablet\":\"px\",\"imageBorderTopWidthMobile\":\"\",\"imageBorderLeftWidthMobile\":\"\",\"imageBorderRightWidthMobile\":\"\",\"imageBorderBottomWidthMobile\":\"\",\"imageBorderTopLeftRadiusMobile\":\"\",\"imageBorderTopRightRadiusMobile\":\"\",\"imageBorderBottomLeftRadiusMobile\":\"\",\"imageBorderBottomRightRadiusMobile\":\"\",\"imageBorderRadiusUnitMobile\":\"px\",\"imageBorderStyle\":\"\",\"imageBorderColor\":\"\",\"imageBorderHColor\":\"\",\"mainTitleBorderTopWidth\":2,\"mainTitleBorderLeftWidth\":0,\"mainTitleBorderRightWidth\":0,\"mainTitleBorderBottomWidth\":2,\"mainTitleBorderTopLeftRadius\":\"\",\"mainTitleBorderTopRightRadius\":\"\",\"mainTitleBorderBottomLeftRadius\":\"\",\"mainTitleBorderBottomRightRadius\":\"\",\"mainTitleBorderRadiusUnit\":\"px\",\"mainTitleBorderTopWidthTablet\":\"\",\"mainTitleBorderLeftWidthTablet\":\"\",\"mainTitleBorderRightWidthTablet\":\"\",\"mainTitleBorderBottomWidthTablet\":\"\",\"mainTitleBorderTopLeftRadiusTablet\":\"\",\"mainTitleBorderTopRightRadiusTablet\":\"\",\"mainTitleBorderBottomLeftRadiusTablet\":\"\",\"mainTitleBorderBottomRightRadiusTablet\":\"\",\"mainTitleBorderRadiusUnitTablet\":\"px\",\"mainTitleBorderTopWidthMobile\":\"\",\"mainTitleBorderLeftWidthMobile\":\"\",\"mainTitleBorderRightWidthMobile\":\"\",\"mainTitleBorderBottomWidthMobile\":\"\",\"mainTitleBorderTopLeftRadiusMobile\":\"\",\"mainTitleBorderTopRightRadiusMobile\":\"\",\"mainTitleBorderBottomLeftRadiusMobile\":\"\",\"mainTitleBorderBottomRightRadiusMobile\":\"\",\"mainTitleBorderRadiusUnitMobile\":\"px\",\"mainTitleBorderStyle\":\"\",\"mainTitleBorderColor\":\"\",\"mainTitleBorderHColor\":\"\"}, '.uagb-block-5cc8c098', {\"lazy\":true,\"slidesPerView\":1,\"navigation\":{\"nextEl\":\".uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .swiper-button-next\",\"prevEl\":\".uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .swiper-button-prev\"},\"keyboard\":{\"enabled\":true}}, [] );\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', () => {\n\t\t\t\t\tconst blockScope = document.querySelector( '.uagb-block-5cc8c098' );\n\t\t\t\t\tif ( ! blockScope ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\t\t\t\t\t\tblockScope.addEventListener('keydown', (event) => {\n\t\t\t\t\t\tif ( 13 === event.keyCode || 32 === event.keyCode ) {\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tblockScope.click();\n\t\t\t\t\t\t}\n\t\t\t\t\t} );\n\n\t\t\t\t\tlet lightboxSwiper = null;\n\t\t\t\t\tlet thumbnailSwiper = null;\n\n\t\t\t\t\t\t\t\t\t\tlet lightboxSettings = {\"lazy\":true,\"slidesPerView\":1,\"navigation\":{\"nextEl\":\".uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .swiper-button-next\",\"prevEl\":\".uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .swiper-button-prev\"},\"keyboard\":{\"enabled\":true}};\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tlightboxSwiper = new Swiper( \".uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main\",\n\t\t\t\t\t\t{\"lazy\":true,\"slidesPerView\":1,\"navigation\":{\"nextEl\":\".uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .swiper-button-next\",\"prevEl\":\".uagb-block-5cc8c098+.spectra-image-gallery__control-lightbox .swiper-button-prev\"},\"keyboard\":{\"enabled\":true}}\t\t\t\t\t);\n\t\t\t\t\tloadLightBoxImages( blockScope, lightboxSwiper, null, {\"block_id\":\"5cc8c098\",\"classMigrate\":true,\"readyToRender\":true,\"mediaGallery\":[{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_2.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1014,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_2.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_7-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_7-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_7-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_7.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1016,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_7.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_7\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_8-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_8-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_8-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_8.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1018,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_8.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_8-2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_13-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_13-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_13-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_13.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1020,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_13.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_13\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_14-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_14-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_14-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_14.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1022,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_14.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_14\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_15-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_15-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_15-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_15.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_15.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_15-2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1026,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block-2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_3-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_3-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_3-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_3.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1028,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_3.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_3\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_4-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_4-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_4-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_4.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1030,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_4.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_4\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_5-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_5-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_5-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_5.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1032,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_5.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_5\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_9-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_9-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_9-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_9.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1034,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_9.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_9-2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_10-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_10-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_10-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_10.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1036,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_10.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_10\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_11-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_11-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_11-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_11.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1038,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_11.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_11-2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_12-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_12-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_12-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_12.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1040,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_12.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_12-2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_1.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1042,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_1.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_1-2\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_6-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_6-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_6-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_6.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1044,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_6.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_6\/\",\"caption\":\"Eco Block Wall\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_16-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_16-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_16-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_16.jpg\",\"height\":1440,\"width\":1920,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1046,\"url\":\"https:\/\/wallsolutions.es\/wp-content\/uploads\/2025\/10\/muro_prebafricado_eco_block_16.jpg\",\"alt\":\"Eco Block Wall\",\"link\":\"https:\/\/wallsolutions.es\/en\/projects\/muro_prebafricado_eco_block_16-2\/\",\"caption\":\"Eco Block Wall\"}],\"mediaIDs\":[1014,1016,1018,1020,1022,1024,1026,1028,1030,1032,1034,1036,1038,1040,1042,1044,1046],\"imageClickEvent\":\"lightbox\",\"captionVisibility\":\"always\",\"imageCaptionAlignment\":\"bottom center\",\"imageCaptionAlignment01\":\"bottom\",\"gridPages\":2,\"feedPagination\":true,\"captionFontSize\":11,\"captionBackgroundEffectAmountHover\":100,\"captionBackgroundColor\":\"rgba(0,0,0,0.3)\",\"paginateDotDistance\":25,\"paginateColor\":\"var(--ast-global-color-0)\",\"paginateColorHover\":\"\",\"imageBoxShadowColor\":\"\",\"tileSize\":0,\"focusList\":[],\"focusListObject\":[],\"feedLayout\":\"grid\",\"imageDisplayCaption\":true,\"galleryImageSize\":\"large\",\"galleryImageSizeTablet\":\"large\",\"galleryImageSizeMobile\":\"medium\",\"disableLazyLoad\":false,\"lightboxDisplayCaptions\":false,\"lightboxThumbnails\":false,\"lightboxDisplayCount\":false,\"lightboxCloseIcon\":\"xmark\",\"lightboxCaptionHeight\":50,\"lightboxCaptionHeightTablet\":\"\",\"lightboxCaptionHeightMobile\":\"\",\"lightboxIconSize\":24,\"lightboxIconSizeTablet\":\"\",\"lightboxIconSizeMobile\":\"\",\"captionDisplayType\":\"overlay\",\"imageCaptionAlignment02\":\"center\",\"imageDefaultCaption\":\"No Caption\",\"captionPaddingTop\":8,\"captionPaddingRight\":8,\"captionPaddingBottom\":8,\"captionPaddingLeft\":8,\"captionPaddingTopTab\":8,\"captionPaddingRightTab\":8,\"captionPaddingBottomTab\":8,\"captionPaddingLeftTab\":8,\"captionPaddingTopMob\":8,\"captionPaddingRightMob\":8,\"captionPaddingBottomMob\":8,\"captionPaddingLeftMob\":8,\"captionPaddingUnit\":\"px\",\"captionPaddingUnitTab\":\"px\",\"captionPaddingUnitMob\":\"px\",\"captionPaddingUnitLink\":true,\"captionGap\":0,\"captionGapUnit\":\"px\",\"columnsDesk\":3,\"columnsTab\":3,\"columnsMob\":2,\"gridImageGap\":8,\"gridImageGapTab\":\"\",\"gridImageGapMob\":\"\",\"gridImageGapUnit\":\"px\",\"gridImageGapUnitTab\":\"px\",\"gridImageGapUnitMob\":\"px\",\"feedMarginTop\":\"\",\"feedMarginRight\":\"\",\"feedMarginBottom\":\"\",\"feedMarginLeft\":\"\",\"feedMarginTopTab\":\"\",\"feedMarginRightTab\":\"\",\"feedMarginBottomTab\":\"\",\"feedMarginLeftTab\":\"\",\"feedMarginTopMob\":\"\",\"feedMarginRightMob\":\"\",\"feedMarginBottomMob\":\"\",\"feedMarginLeftMob\":\"\",\"feedMarginUnit\":\"px\",\"feedMarginUnitTab\":\"px\",\"feedMarginUnitMob\":\"px\",\"feedMarginUnitLink\":true,\"carouselStartAt\":0,\"carouselSquares\":false,\"carouselLoop\":true,\"carouselAutoplay\":true,\"carouselAutoplaySpeed\":2000,\"carouselPauseOnHover\":true,\"carouselTransitionSpeed\":500,\"gridPageNumber\":1,\"paginateUseArrows\":true,\"paginateUseDots\":true,\"paginateUseLoader\":true,\"paginateLimit\":9,\"paginateButtonAlign\":\"center\",\"paginateButtonText\":\"Load More Images\",\"paginateButtonPaddingTop\":\"\",\"paginateButtonPaddingRight\":\"\",\"paginateButtonPaddingBottom\":\"\",\"paginateButtonPaddingLeft\":\"\",\"paginateButtonPaddingTopTab\":\"\",\"paginateButtonPaddingRightTab\":\"\",\"paginateButtonPaddingBottomTab\":\"\",\"paginateButtonPaddingLeftTab\":\"\",\"paginateButtonPaddingTopMob\":\"\",\"paginateButtonPaddingRightMob\":\"\",\"paginateButtonPaddingBottomMob\":\"\",\"paginateButtonPaddingLeftMob\":\"\",\"paginateButtonPaddingUnit\":\"px\",\"paginateButtonPaddingUnitTab\":\"px\",\"paginateButtonPaddingUnitMob\":\"px\",\"paginateButtonPaddingUnitLink\":true,\"imageEnableZoom\":true,\"imageZoomType\":\"zoom-in\",\"captionBackgroundEnableBlur\":false,\"captionBackgroundBlurAmount\":0,\"captionBackgroundBlurAmountHover\":5,\"lightboxEdgeDistance\":10,\"lightboxEdgeDistanceTablet\":\"\",\"lightboxEdgeDistanceMobile\":\"\",\"lightboxBackgroundEnableBlur\":true,\"lightboxBackgroundBlurAmount\":5,\"lightboxBackgroundColor\":\"rgba(0,0,0,0.75)\",\"lightboxIconColor\":\"rgba(255,255,255,1)\",\"lightboxCaptionColor\":\"rgba(255,255,255,1)\",\"lightboxCaptionBackgroundColor\":\"rgba(0,0,0,1)\",\"captionLoadGoogleFonts\":false,\"captionFontFamily\":\"Default\",\"captionFontWeight\":\"\",\"captionFontStyle\":\"normal\",\"captionTransform\":\"\",\"captionDecoration\":\"none\",\"captionFontSizeType\":\"px\",\"captionFontSizeTab\":\"\",\"captionFontSizeMob\":\"\",\"captionLineHeightType\":\"em\",\"captionLineHeight\":\"\",\"captionLineHeightTab\":\"\",\"captionLineHeightMob\":\"\",\"loadMoreLoadGoogleFonts\":false,\"loadMoreFontFamily\":\"Default\",\"loadMoreFontWeight\":\"\",\"loadMoreFontStyle\":\"normal\",\"loadMoreTransform\":\"\",\"loadMoreDecoration\":\"none\",\"loadMoreFontSizeType\":\"px\",\"loadMoreFontSize\":\"\",\"loadMoreFontSizeTab\":\"\",\"loadMoreFontSizeMob\":\"\",\"loadMoreLineHeightType\":\"em\",\"loadMoreLineHeight\":\"\",\"loadMoreLineHeightTab\":\"\",\"loadMoreLineHeightMob\":\"\",\"lightboxLoadGoogleFonts\":false,\"lightboxFontFamily\":\"Default\",\"lightboxFontWeight\":\"\",\"lightboxFontStyle\":\"normal\",\"lightboxTransform\":\"\",\"lightboxDecoration\":\"none\",\"lightboxFontSizeType\":\"px\",\"lightboxFontSize\":\"\",\"lightboxFontSizeTab\":\"\",\"lightboxFontSizeMob\":\"\",\"lightboxLineHeightType\":\"em\",\"lightboxLineHeight\":\"\",\"lightboxLineHeightTab\":\"\",\"lightboxLineHeightMob\":\"\",\"captionBackgroundEffect\":\"none\",\"captionBackgroundEffectHover\":\"none\",\"captionBackgroundEffectAmount\":100,\"captionColor\":\"rgba(255,255,255,1)\",\"captionColorHover\":\"rgba(255,255,255,1)\",\"captionBackgroundColorHover\":\"rgba(0,0,0,0.75)\",\"overlayColor\":\"rgba(0,0,0,0)\",\"overlayColorHover\":\"rgba(0,0,0,0)\",\"captionSeparateColors\":false,\"paginateArrowDistance\":-24,\"paginateArrowDistanceUnit\":\"px\",\"paginateArrowSize\":24,\"paginateDotDistanceUnit\":\"px\",\"paginateLoaderSize\":18,\"paginateButtonTextColor\":\"\",\"paginateButtonTextColorHover\":\"\",\"imageBoxShadowHOffset\":0,\"imageBoxShadowVOffset\":0,\"imageBoxShadowBlur\":\"\",\"imageBoxShadowSpread\":\"\",\"imageBoxShadowPosition\":\"outset\",\"imageBoxShadowColorHover\":\"\",\"imageBoxShadowHOffsetHover\":0,\"imageBoxShadowVOffsetHover\":0,\"imageBoxShadowBlurHover\":\"\",\"imageBoxShadowSpreadHover\":\"\",\"imageBoxShadowPositionHover\":\"outset\",\"arrowBorderTopWidth\":4,\"arrowBorderLeftWidth\":4,\"arrowBorderRightWidth\":4,\"arrowBorderBottomWidth\":4,\"arrowBorderTopLeftRadius\":50,\"arrowBorderTopRightRadius\":50,\"arrowBorderBottomLeftRadius\":50,\"arrowBorderBottomRightRadius\":50,\"arrowBorderRadiusUnit\":\"px\",\"arrowBorderTopWidthTablet\":\"\",\"arrowBorderLeftWidthTablet\":\"\",\"arrowBorderRightWidthTablet\":\"\",\"arrowBorderBottomWidthTablet\":\"\",\"arrowBorderTopLeftRadiusTablet\":\"\",\"arrowBorderTopRightRadiusTablet\":\"\",\"arrowBorderBottomLeftRadiusTablet\":\"\",\"arrowBorderBottomRightRadiusTablet\":\"\",\"arrowBorderRadiusUnitTablet\":\"px\",\"arrowBorderTopWidthMobile\":\"\",\"arrowBorderLeftWidthMobile\":\"\",\"arrowBorderRightWidthMobile\":\"\",\"arrowBorderBottomWidthMobile\":\"\",\"arrowBorderTopLeftRadiusMobile\":\"\",\"arrowBorderTopRightRadiusMobile\":\"\",\"arrowBorderBottomLeftRadiusMobile\":\"\",\"arrowBorderBottomRightRadiusMobile\":\"\",\"arrowBorderRadiusUnitMobile\":\"px\",\"arrowBorderStyle\":\"none\",\"arrowBorderColor\":\"\",\"arrowBorderHColor\":\"\",\"btnBorderTopWidth\":\"\",\"btnBorderLeftWidth\":\"\",\"btnBorderRightWidth\":\"\",\"btnBorderBottomWidth\":\"\",\"btnBorderTopLeftRadius\":\"\",\"btnBorderTopRightRadius\":\"\",\"btnBorderBottomLeftRadius\":\"\",\"btnBorderBottomRightRadius\":\"\",\"btnBorderRadiusUnit\":\"px\",\"btnBorderTopWidthTablet\":\"\",\"btnBorderLeftWidthTablet\":\"\",\"btnBorderRightWidthTablet\":\"\",\"btnBorderBottomWidthTablet\":\"\",\"btnBorderTopLeftRadiusTablet\":\"\",\"btnBorderTopRightRadiusTablet\":\"\",\"btnBorderBottomLeftRadiusTablet\":\"\",\"btnBorderBottomRightRadiusTablet\":\"\",\"btnBorderRadiusUnitTablet\":\"px\",\"btnBorderTopWidthMobile\":\"\",\"btnBorderLeftWidthMobile\":\"\",\"btnBorderRightWidthMobile\":\"\",\"btnBorderBottomWidthMobile\":\"\",\"btnBorderTopLeftRadiusMobile\":\"\",\"btnBorderTopRightRadiusMobile\":\"\",\"btnBorderBottomLeftRadiusMobile\":\"\",\"btnBorderBottomRightRadiusMobile\":\"\",\"btnBorderRadiusUnitMobile\":\"px\",\"btnBorderStyle\":\"\",\"btnBorderColor\":\"\",\"btnBorderHColor\":\"\",\"imageBorderTopWidth\":\"\",\"imageBorderLeftWidth\":\"\",\"imageBorderRightWidth\":\"\",\"imageBorderBottomWidth\":\"\",\"imageBorderTopLeftRadius\":\"\",\"imageBorderTopRightRadius\":\"\",\"imageBorderBottomLeftRadius\":\"\",\"imageBorderBottomRightRadius\":\"\",\"imageBorderRadiusUnit\":\"px\",\"imageBorderTopWidthTablet\":\"\",\"imageBorderLeftWidthTablet\":\"\",\"imageBorderRightWidthTablet\":\"\",\"imageBorderBottomWidthTablet\":\"\",\"imageBorderTopLeftRadiusTablet\":\"\",\"imageBorderTopRightRadiusTablet\":\"\",\"imageBorderBottomLeftRadiusTablet\":\"\",\"imageBorderBottomRightRadiusTablet\":\"\",\"imageBorderRadiusUnitTablet\":\"px\",\"imageBorderTopWidthMobile\":\"\",\"imageBorderLeftWidthMobile\":\"\",\"imageBorderRightWidthMobile\":\"\",\"imageBorderBottomWidthMobile\":\"\",\"imageBorderTopLeftRadiusMobile\":\"\",\"imageBorderTopRightRadiusMobile\":\"\",\"imageBorderBottomLeftRadiusMobile\":\"\",\"imageBorderBottomRightRadiusMobile\":\"\",\"imageBorderRadiusUnitMobile\":\"px\",\"imageBorderStyle\":\"\",\"imageBorderColor\":\"\",\"imageBorderHColor\":\"\",\"mainTitleBorderTopWidth\":2,\"mainTitleBorderLeftWidth\":0,\"mainTitleBorderRightWidth\":0,\"mainTitleBorderBottomWidth\":2,\"mainTitleBorderTopLeftRadius\":\"\",\"mainTitleBorderTopRightRadius\":\"\",\"mainTitleBorderBottomLeftRadius\":\"\",\"mainTitleBorderBottomRightRadius\":\"\",\"mainTitleBorderRadiusUnit\":\"px\",\"mainTitleBorderTopWidthTablet\":\"\",\"mainTitleBorderLeftWidthTablet\":\"\",\"mainTitleBorderRightWidthTablet\":\"\",\"mainTitleBorderBottomWidthTablet\":\"\",\"mainTitleBorderTopLeftRadiusTablet\":\"\",\"mainTitleBorderTopRightRadiusTablet\":\"\",\"mainTitleBorderBottomLeftRadiusTablet\":\"\",\"mainTitleBorderBottomRightRadiusTablet\":\"\",\"mainTitleBorderRadiusUnitTablet\":\"px\",\"mainTitleBorderTopWidthMobile\":\"\",\"mainTitleBorderLeftWidthMobile\":\"\",\"mainTitleBorderRightWidthMobile\":\"\",\"mainTitleBorderBottomWidthMobile\":\"\",\"mainTitleBorderTopLeftRadiusMobile\":\"\",\"mainTitleBorderTopRightRadiusMobile\":\"\",\"mainTitleBorderBottomLeftRadiusMobile\":\"\",\"mainTitleBorderBottomRightRadiusMobile\":\"\",\"mainTitleBorderRadiusUnitMobile\":\"px\",\"mainTitleBorderStyle\":\"\",\"mainTitleBorderColor\":\"\",\"mainTitleBorderHColor\":\"\"}, thumbnailSwiper );\n\t\t\t\t\t\t\t\tconst regexCustomURL = new RegExp( '^((http|https):\/\/)(www.)?[a-zA-Z0-9@:%._\\+~#?&\/\/=\\-]{2,256}\\.[a-z]{2,6}\\b([-a-zA-Z0-9@:%._\\+~#?&\/\/=]*)$' );\n\t\t\tconst customLinks = {};\n\t\t\tconst customLinksBehaviour = {};\n\n\t\t\tconst getCustomURL = ( caption ) => {\n\t\t\t\tif ( ! customLinks ) {\n\t\t\t\t\treturn undefined;\n\t\t\t\t}\n\t\t\t\tconst imageID = parseInt( caption.getAttribute( 'data-spectra-gallery-image-id' ) );\n\t\t\t\treturn ( regexCustomURL.test( customLinks[ imageID ] ) ? customLinks[ imageID ] : undefined );\n\t\t\t}\n\n\t\t\tconst getCustomLinkBehaviour = (caption) => {\n\t\t\t\tif (!customLinksBehaviour) {\n\t\t\t\t\treturn true;\n\t\t\t\t}\n\t\t\t\tconst imageId = parseInt(caption.getAttribute('data-spectra-gallery-image-id'));\n\t\t\t\treturn !(customLinksBehaviour[imageId] === true);\n\t\t\t};\n\n\t\t\tconst captions = lightboxSwiper.el.querySelectorAll( '.spectra-image-gallery__control-lightbox--caption' );\n\t\t\tfor ( let i = 0; i < captions.length; i++ ) {\n\t\t\t\tconst customURL = getCustomURL( captions[ i ] );\n\t\t\t\tif ( customURL ) {\n\t\t\t\t\tconst anchor = document.createElement( 'a' );\n\t\t\t\t\tanchor.target = getCustomLinkBehaviour( captions[ i ] ) ? '_blank' : '_self';\n\t\t\t\t\tanchor.rel = 'noopener noreferrer';\n\t\t\t\t\tanchor.href = customURL;\n\t\t\t\t\tanchor.innerHTML = captions[ i ].innerHTML;\n\t\t\t\t\tcaptions[ i ].textContent = '';\n\t\t\t\t\tcaptions[ i ].appendChild( anchor );\n\t\t\t\t}\n\t\t\t}\n\t\t\t\t\t\t} );\n\t\t\tjQuery(document).ready(function(){if(window.matchMedia&&window.matchMedia(\"(hover:none)\").matches){jQuery(\".wp-block-uagb-image-gallery.uagb-block-5cc8c098\").addClass(\"spectra-touch-device\");}}); });\";s:18:\"current_block_list\";a:13:{i:0;s:14:\"uagb\/container\";i:1;s:21:\"uagb\/advanced-heading\";i:2;s:25:\"uagb\/animations-extension\";i:5;s:12:\"core\/heading\";i:6;s:18:\"uagb\/image-gallery\";i:7;s:11:\"core\/spacer\";i:9;s:13:\"uagb\/info-box\";i:10;s:11:\"core\/search\";i:11;s:10:\"core\/group\";i:12;s:17:\"core\/latest-posts\";i:13;s:20:\"core\/latest-comments\";i:14;s:13:\"core\/archives\";i:15;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1784090207\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Mentaliza","author_link":"https:\/\/wallsolutions.es\/en\/author\/mentaliza\/"},"uagb_comment_info":0,"uagb_excerpt":"OUR PORTFOLIO Showcasing Excellence in Retaining Walls and Slope Stabilisation. Eco Wall Iron Grid (Gaviones) Eco Block","_links":{"self":[{"href":"https:\/\/wallsolutions.es\/en\/wp-json\/wp\/v2\/pages\/862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wallsolutions.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wallsolutions.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wallsolutions.es\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wallsolutions.es\/en\/wp-json\/wp\/v2\/comments?post=862"}],"version-history":[{"count":15,"href":"https:\/\/wallsolutions.es\/en\/wp-json\/wp\/v2\/pages\/862\/revisions"}],"predecessor-version":[{"id":1166,"href":"https:\/\/wallsolutions.es\/en\/wp-json\/wp\/v2\/pages\/862\/revisions\/1166"}],"wp:attachment":[{"href":"https:\/\/wallsolutions.es\/en\/wp-json\/wp\/v2\/media?parent=862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}